{"id":243821,"date":"2024-11-06T15:55:34","date_gmt":"2024-11-06T14:55:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=243821"},"modified":"2024-11-06T15:59:35","modified_gmt":"2024-11-06T14:59:35","slug":"scontro-tra-unauto-e-una-moto-grave-un-ragazzo-trasportato-a-cosenza-in-elisoccorso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/scontro-tra-unauto-e-una-moto-grave-un-ragazzo-trasportato-a-cosenza-in-elisoccorso\/","title":{"rendered":"Scontro tra un&#8217;auto e una moto. Grave un ragazzo, trasportato a Cosenza in elisoccorso"},"content":{"rendered":"<p>CORIGLIANO &#8211; ROSSANO (CS) &#8211; <strong>Un ragazzo, a bordo di una moto, \u00e8 rimasto gravemente ferito<\/strong> a seguito di un incidente avvenuto<strong> in via Michele Bianchi, nell&#8217;area urbana di Rossano in Contrada Petra<\/strong>. L&#8217;impatto \u00e8 avvenuto poco dopo le 13:00, ed ha coinvolto la moto guidata dal giovane <strong>ed un&#8217;automobile<\/strong>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Incidente-Rossano.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-243825 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Incidente-Rossano.jpg\" alt=\"Incidente Rossano\" width=\"515\" height=\"319\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Incidente-Rossano.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Incidente-Rossano-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Incidente-Rossano-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Incidente-Rossano-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Incidente-Rossano-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Incidente-Rossano-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Incidente-Rossano-356x220.jpg 356w\" sizes=\"auto, (max-width: 515px) 100vw, 515px\" \/><\/a><\/p>\n<p>Sul posto \u00e8 prontamente intervenuta un&#8217;ambulanza del 118 che <strong>ha soccorso e trasportato il giovane al Giannettasio<\/strong>.<strong> Ma vista la gravit\u00e0 delle ferite il ragazzo \u00e8 stato successivamente trasferito all&#8217;ospedale di Cosenza in elisoccorso<\/strong>. L&#8217;area dell&#8217;incidente \u00e8 stata transennata e sul posto sono intervenuti gli uomini della municipale e<strong> i carabinieri per i rilievi del caso<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO &#8211; ROSSANO (CS) &#8211; Un ragazzo, a bordo di una moto, \u00e8 rimasto gravemente ferito a seguito di un incidente avvenuto in via Michele Bianchi, nell&#8217;area urbana di Rossano in Contrada Petra. L&#8217;impatto \u00e8 avvenuto poco dopo le 13:00, ed ha coinvolto la moto guidata dal giovane ed un&#8217;automobile. Sul posto \u00e8 prontamente intervenuta [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":233621,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[19],"class_list":["post-243821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/243821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=243821"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/243821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/233621"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=243821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=243821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=243821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}