{"id":244431,"date":"2024-11-14T11:47:27","date_gmt":"2024-11-14T10:47:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=244431"},"modified":"2024-11-14T11:47:27","modified_gmt":"2024-11-14T10:47:27","slug":"referendum-citta-unica-a-rende-saranno-spostate-tre-sezioni-elettorali","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/referendum-citta-unica-a-rende-saranno-spostate-tre-sezioni-elettorali\/","title":{"rendered":"Referendum Citt\u00e0 Unica, a Rende saranno spostate tre sezioni elettorali"},"content":{"rendered":"<p>RENDE &#8211; Il Comune informa la cittadinanza che <strong>alcune sezioni elettorali<\/strong> saranno <strong>spostate<\/strong> rispetto alla loro tradizionale ubicazione. Il riferimento \u00e8 al Referendum consultivo indetto per il <strong>prossimo 1\u00b0 dicembre<\/strong>. A causa di <strong>lavori<\/strong> di <strong>ristrutturazione<\/strong> e adeguamento del plesso scolastico sito presso la <strong>scuola materna di Parco Robinson<\/strong>, alcune sezioni non saranno disponibili nei consueti locali.<\/p>\n<p>Le sezioni elettorali interessate dallo spostamento sono le <strong>numero 10, 20 e 24<\/strong>. Le prime due sono state trasferite presso la <strong>scuola elementare di Via Giotto<\/strong> mentre la n. 24, presso la <strong>scuola media di via A. Panagulis.<\/strong><\/p>\n<p>Gli elettori pertanto potranno recarsi a votare presso i seggi di nuova ubicazione semplicemente presentando la tessera elettorale e un documento di identit\u00e0 in corso di validit\u00e0, senza bisogno di chiedere l&#8217;aggiornamento d&#8217;indirizzo della nuova ubicazione della sezione. Per informazioni e chiarimenti \u00e8 possibile contattare l&#8217;ufficio elettorale ai seguenti numeri: 0984 8284325; 0984 8284209; 0984 8284427; 098408482354 oppure consultando il sito web del <a href=\"https:\/\/www.comune.rende.cs.it\/\" rel=\"noopener\">Comune di Rende<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Il Comune informa la cittadinanza che alcune sezioni elettorali saranno spostate rispetto alla loro tradizionale ubicazione. Il riferimento \u00e8 al Referendum consultivo indetto per il prossimo 1\u00b0 dicembre. A causa di lavori di ristrutturazione e adeguamento del plesso scolastico sito presso la scuola materna di Parco Robinson, alcune sezioni non saranno disponibili nei [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":197968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-244431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=244431"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244431\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/197968"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=244431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=244431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=244431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}