{"id":244449,"date":"2024-11-14T18:00:57","date_gmt":"2024-11-14T17:00:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=244449"},"modified":"2024-11-14T16:02:57","modified_gmt":"2024-11-14T15:02:57","slug":"ndrangheta-sequestrati-beni-per-6-milioni-a-rosario-barbaro-boss-di-plati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ndrangheta-sequestrati-beni-per-6-milioni-a-rosario-barbaro-boss-di-plati\/","title":{"rendered":"&#8216;Ndrangheta: sequestrati beni per 6 milioni a Rosario Barbaro, boss di Plat\u00ec"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Duro colpo ai patrimoni della &#8216;ndrangheta. Sotto sequestro beni per un valore di sei milioni di euro a <strong>Rosario Barbaro, di 84 anni<\/strong>, ritenuto il capostipite dell&#8217;omonima cosca di Plat\u00ec. Titolare di fatto di numerosi fabbricati, terreni ed importanti attivit\u00e0 commerciali, secondo gli inquirenti, <strong>Barbaro, detto &#8220;Rosi da Massara&#8221;<\/strong>, riveste un <strong>ruolo apicale all&#8217;interno di una famiglia di &#8216;ndrangheta di Plat\u00ec<\/strong> la cui attivit\u00e0 si estende su tutto il territorio nazionale, nonch\u00e9 all&#8217;estero.<\/p>\n<p>Gi\u00e0 destinatario nel lontano <strong>1965<\/strong> di un<strong> decreto di appartenenza ad associazione mafiosa<\/strong> a firma dell&#8217;allora questore di Reggio Calabria, nel corso dell&#8217;ultimo cinquantennio Barbaro ha rivestito un <strong>ruolo via via crescente nell&#8217;ambito della consorteria criminale<\/strong>, sino ad essere stato indicato univocamente quale vertice della stessa. La sua figura criminale \u00e8 stata oggetto di svariate operazioni di polizia giudiziaria che hanno interessato il versante ionico della provincia reggina. In particolare, Rosario Barbaro \u00e8 stato coinvolto nelle operazioni &#8220;Reale&#8221;, &#8220;Marine&#8221;, &#8220;Mandamento Ionico&#8221; e &#8220;Saggezza&#8221; e condannato per associazione a delinquere di stampo mafioso.<\/p>\n<p>Le indagini condotte dagli investigatori del Centro operativo Dia di Reggio Calabria guidati dal colonnello Mario Intelisano hanno consentito di <strong>ricostruire le acquisizioni patrimoniali del boss sin dall&#8217;anno 1961<\/strong>, e di individuare il patrimonio direttamente e indirettamente nella disponibilit\u00e0 di Barbaro, il cui valore sarebbe risultato sproporzionato rispetto alla sua capacit\u00e0 reddituale. Da qui il sequestro disposto dal Tribunale che ha riguardato <strong>cinque societ\u00e0 comprensive dell&#8217;intero patrimonio aziendale<\/strong>, di cui t<strong>re ditte individuali operanti nel settore agricolo, un circolo privato e un&#8217;attivit\u00e0 di ristorazione.<\/strong> Si tratta di <strong>un locale<\/strong> dove, stando agli inquirenti e alla cronaca giornalistica, sono stati <strong>celebrati matrimoni di significativo interesse criminale<\/strong> tra appartenenti ad importanti e storiche famiglie di &#8216;ndrangheta.<\/p>\n<p>Matrimoni dove sarebbero state conferite anche nomine alle pi\u00f9 alte cariche dell&#8217;organizzazione criminale in senso unitario. Oltre alle disponibilit\u00e0 finanziarie, sono stati sequestrati 14 immobili e 40 appezzamenti di terreno nella provincia di Reggio Calabria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Duro colpo ai patrimoni della &#8216;ndrangheta. Sotto sequestro beni per un valore di sei milioni di euro a Rosario Barbaro, di 84 anni, ritenuto il capostipite dell&#8217;omonima cosca di Plat\u00ec. Titolare di fatto di numerosi fabbricati, terreni ed importanti attivit\u00e0 commerciali, secondo gli inquirenti, Barbaro, detto &#8220;Rosi da Massara&#8221;, riveste un ruolo [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":159010,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-244449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=244449"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244449\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/159010"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=244449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=244449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=244449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}