{"id":244616,"date":"2024-11-15T21:30:04","date_gmt":"2024-11-15T20:30:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=244616"},"modified":"2024-11-15T20:32:37","modified_gmt":"2024-11-15T19:32:37","slug":"m5s-e-pd-riaprire-la-strada-sila-mare-la-regione-intervenga-con-urgenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/m5s-e-pd-riaprire-la-strada-sila-mare-la-regione-intervenga-con-urgenza\/","title":{"rendered":"M5S e PD: &#8220;Riaprire la strada Sila Mare, la Regione intervenga con urgenza&#8221;"},"content":{"rendered":"<p>COSENZA -&#8220;Un&#8217;infrastruttura strategica per il territorio, una comunit\u00e0 in attesa di risposte concrete&#8221;. \u00c8 con queste premesse che <strong>Davide Tavernise,<\/strong> capogruppo del Movimento 5 Stelle, e <strong>Domenico Bevacqua<\/strong>, capogruppo del Partito Democratico, hanno presentato <strong>un&#8217;interrogazione al Presidente della Giunta regionale, Roberto Occhiuto<\/strong>, per fare luce sui <strong>ritardi nella riapertura del tratto della Strada Sila Mare<\/strong> tra il ponte Manco\/Destro e il ponte di Caloveto.<strong> Riapertura prevista ad agosto 2024.<\/strong> La Strada Statale 177, nota come Sila Mare, rappresenta un&#8217;arteria cruciale per il collegamento tra le aree interne dell&#8217;altopiano silano e la fascia costiera ionica cosentina. Tuttavia, nonostante le promesse di riapertura per l&#8217;estate 2024, i lavori su questo <strong>tratto, lungo circa 6 chilometri<\/strong>, procedono a rilento,<strong> lasciando il territorio isolato<\/strong> e la comunit\u00e0 in difficolt\u00e0.<\/p>\n<p>&#8220;La Regione Calabria deve intervenire con decisione &#8211; affermano Tavernise e Bevacqua -. Non possiamo permettere che un&#8217;opera cos\u00ec importante subisca ulteriori ritardi. La Sila Mare \u00e8 un simbolo di sviluppo e di connessione tra territori. Chiediamo al Presidente Occhiuto di<strong> indicare tempi certi<\/strong> e non pi\u00f9 prorogabili per la riapertura del tratto e il rispetto del cronoprogramma per il completamento dell&#8217;intera opera&#8221;. I consiglieri regionali sottolineano come &#8220;il <strong><a href=\"https:\/\/quicosenza.it\/news\/provincia\/crollo-ponte-sul-trionto-dal-ministro-salvini-un-decreto-longobucco\" target=\"_blank\" rel=\"noopener\">crollo del viadotto Ortiano II,<\/a><\/strong> avvenuto nel maggio 2023, abbia aggravato una situazione gi\u00e0 critica, portando all&#8217;isolamento di Longobucco e dei comuni limitrofi. Nonostante il via libera del Ministero delle Infrastrutture e Trasporti per l&#8217;utilizzo di 9 milioni di euro e le rassicurazioni ricevute, il cronoprogramma non \u00e8 stato rispettato. I cittadini hanno diritto a risposte chiare e a un&#8217;azione concreta per accelerare i lavori.&#8221;<\/p>\n<p>&#8220;La Sila Mare &#8211; aggiungono Tavernise e Bevacqua -, oltre a garantire sicurezza e rapidit\u00e0 nei collegamenti, rappresenta una leva strategica per lo sviluppo economico e turistico della Calabria. Completare l&#8217;asse viario Mirto Crosia-Longobucco permetterebbe di collegare in meno di 30 minuti la costa ionica con il Parco Nazionale della Sila. Un&#8217;opportunit\u00e0 unica per migliorare la competitivit\u00e0 del territorio e valorizzarne il potenziale. L&#8217;interrogazione presentata \u00e8 un segnale di attenzione verso le esigenze della popolazione e un richiamo alla necessit\u00e0 di una governance efficiente &#8211; chiosano i Capogruppo -. \u00c8 inaccettabile che i ritardi nei lavori continuino a penalizzare intere comunit\u00e0. Il nostro impegno \u00e8 per una Calabria pi\u00f9 connessa, moderna e inclusiva&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA -&#8220;Un&#8217;infrastruttura strategica per il territorio, una comunit\u00e0 in attesa di risposte concrete&#8221;. \u00c8 con queste premesse che Davide Tavernise, capogruppo del Movimento 5 Stelle, e Domenico Bevacqua, capogruppo del Partito Democratico, hanno presentato un&#8217;interrogazione al Presidente della Giunta regionale, Roberto Occhiuto, per fare luce sui ritardi nella riapertura del tratto della Strada Sila Mare [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":244619,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-244616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=244616"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244616\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/244619"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=244616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=244616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=244616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}