{"id":244694,"date":"2024-11-17T12:02:20","date_gmt":"2024-11-17T11:02:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=244694"},"modified":"2024-11-17T12:02:20","modified_gmt":"2024-11-17T11:02:20","slug":"rende-allarme-esche-avvelenate-ordinanza-del-comune-sul-pericolo-e-apertura-di-unindagine","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/rende-allarme-esche-avvelenate-ordinanza-del-comune-sul-pericolo-e-apertura-di-unindagine\/","title":{"rendered":"Rende: allarme esche avvelenate. Ordinanza del Comune sul pericolo e apertura di un\u2019indagine"},"content":{"rendered":"<p>RENDE \u2013 <strong>Bocconi avvelenati a Rende,<\/strong> in particolare nella zona di <strong>Surdo<\/strong>. Tutto \u00e8 partito a inizio settimana, quando l\u2019istituto Zooprifilattico Sperimentale del Mezzogiorno, <strong>ha comunicato al Comune di Rende il sospetto avvelenamento di un gatto<\/strong> ritrovato morto <strong>in Via Alessandro Manzoni<\/strong> in contrada Pirelli. Accertamenti successivi hanno confermato che la morte del gatto <strong>\u00e8 stata provocata da un\u2019esca avvelenata<\/strong>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Ordinanza-Rende-.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-244696 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Ordinanza-Rende-.jpg\" alt=\"Ordinanza Rende\" width=\"504\" height=\"279\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Ordinanza-Rende-.jpg 1799w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Ordinanza-Rende--300x166.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Ordinanza-Rende--1024x566.jpg 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Ordinanza-Rende--768x425.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Ordinanza-Rende--1536x850.jpg 1536w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Ordinanza-Rende--759x420.jpg 759w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Ordinanza-Rende--150x83.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Ordinanza-Rende--696x385.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Ordinanza-Rende--1068x591.jpg 1068w\" sizes=\"auto, (max-width: 504px) 100vw, 504px\" \/><\/a><\/p>\n<h3>L&#8217;ordinanza deli commissari<\/h3>\n<p><strong>Con una ordinanza della commissione straordinaria<\/strong> del Comune di Rende, sono state date disposizioni per l\u2019<strong>apertura di un\u2019indagine<\/strong> da effettuare in collaborazione con le Autorit\u00e0 competenti, <strong>l\u2019immediata segnalazione, tramite appositi cartelli, della zona sede di pericoli per bocconi presumibilmente avvelenat<\/strong>i e\/o per la presenza di sostanze venefiche.<\/p>\n<p>L&#8217;ordinanza dei commissari dispone anche il<strong> sopralluogo della zona interessata<\/strong>, al fine di accertare <strong>l\u2019eventuale presenza di ulteriori sostanze venefiche<\/strong> (veleno, esche avvelenate e similari), nel luogo di ritrovamento degli <strong>animali morti per avvelenamento ed in quelle immediatamente limitrofe.<\/strong> Ancora, di provvedere, sulla base delle segnalazioni della presenza di ulteriori sostanze venefiche, alle <strong>operazioni di bonifica dell\u2019area interessata dall\u2019avvelenamento<\/strong> al fine di rimuovere eventuali prodotti tossici presenti. La polizia municipale chiede a tutti i cittadini di <strong>prestare la massima allerta<\/strong> e, in caso di rinvenimento di tracce,<strong> di darne subito comunicazione al servizio sanitario del Comune, <\/strong>al comando di Polizia municipale o ai competenti uffici dell&#8217;Asp senza toccare, rimuovere o desperdere le tracce<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE \u2013 Bocconi avvelenati a Rende, in particolare nella zona di Surdo. Tutto \u00e8 partito a inizio settimana, quando l\u2019istituto Zooprifilattico Sperimentale del Mezzogiorno, ha comunicato al Comune di Rende il sospetto avvelenamento di un gatto ritrovato morto in Via Alessandro Manzoni in contrada Pirelli. Accertamenti successivi hanno confermato che la morte del gatto \u00e8 [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":244695,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[19],"class_list":["post-244694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=244694"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/244695"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=244694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=244694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=244694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}