{"id":244792,"date":"2024-11-18T18:08:17","date_gmt":"2024-11-18T17:08:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=244792"},"modified":"2024-11-18T18:08:17","modified_gmt":"2024-11-18T17:08:17","slug":"stalking-allex-compagno-applicato-braccialetto-elettronico-ad-una-donna","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/stalking-allex-compagno-applicato-braccialetto-elettronico-ad-una-donna\/","title":{"rendered":"Stalking all\u2019ex compagno: applicato braccialetto elettronico ad una donna"},"content":{"rendered":"<p>CROTONE &#8211;\u00a0Personale della Polizia di Stato della questura ha dato esecuzione all\u2019ordinanza della misura cautelare del divieto di avvicinamento con applicazione del braccialetto elettronico, a carico di una donna crotonese di 31 anni, indagata per il reato di atti persecutori commessi nei confronti dell\u2019ex compagno. Il provvedimento \u00e8 stato emesso a seguito delle indagini, conseguenti alla denuncia sporta dall\u2019uomo, condotte dagli operatori della squadra mobile che hanno immediatamente attivato la procedura del cosiddetto \u201ccodice rosso\u201d.<\/p>\n<p>Dagli accertamenti effettuati \u00e8 emerso che\u00a0<strong>la donna aveva commesso condotte intimidatorie e moleste nei confronti dell\u2019uomo attraverso pedinamenti, aggressioni fisiche e minacce; \u00a0inoltre, in pochi mesi, la donna aveva effettuato circa tremila chiamate telefoniche e tentativi di chiamate anonime all\u2019utenza del ex compagno<\/strong>.\u00a0Le puntuali dichiarazioni della persona offesa, riscontrate anche da elementi oggettivi e dalle dichiarazioni di soggetti informati, hanno indotto la Procura di Crotone a richiedere al Gip una misura cautelare a carico della donna, la quale non potr\u00e0 avvicinarsi all\u2019uomo e ai luoghi da lui frequentati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211;\u00a0Personale della Polizia di Stato della questura ha dato esecuzione all\u2019ordinanza della misura cautelare del divieto di avvicinamento con applicazione del braccialetto elettronico, a carico di una donna crotonese di 31 anni, indagata per il reato di atti persecutori commessi nei confronti dell\u2019ex compagno. Il provvedimento \u00e8 stato emesso a seguito delle indagini, conseguenti [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":243737,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-244792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=244792"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/243737"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=244792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=244792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=244792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}