{"id":244797,"date":"2024-11-19T07:03:34","date_gmt":"2024-11-19T06:03:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=244797"},"modified":"2024-11-19T07:26:17","modified_gmt":"2024-11-19T06:26:17","slug":"cosenza-condannata-a-tre-anni-lex-prefetto-paola-galeone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-condannata-a-tre-anni-lex-prefetto-paola-galeone\/","title":{"rendered":"Cosenza, condannata a tre anni l&#8217;ex prefetto Paola Galeone"},"content":{"rendered":"<p>COSENZA &#8211; E&#8217; stata condannata a<strong> tre anni di reclusione<\/strong> l\u2019ex prefetto di Cosenza, Paola Galeone, accusata di induzione indebita alla corruzione e rivelazione di segreti d\u2019ufficio. Riqualificata l\u2019imputazione in istigazione alla corruzione, l\u2019imputata \u00e8 stata assolta dall\u2019accusa di rivelazione di segreti d\u2019ufficio. Disposta inoltre, <strong>l\u2019interdizione perpetua dai pubblici uffici.<\/strong> Per l&#8217;accusa l&#8217;ex prefetto avrebbe chiesto una sorta di \u201cmazzetta\u201d attraverso l\u2019emissione di una fattura falsa da<strong> 1.200 euro all&#8217;imprenditrice Cinzia Falcone<\/strong>, presidente dell\u2019associazione \u201cAnimed\u201d, per una somma del fondo di rappresentanza della Prefettura.<\/p>\n<p>La vicenda risale al <strong>2019<\/strong> e a denunciarla era stata l&#8217;imprenditrice cosentina la quale raccont\u00f2 che Paola Galeone le aveva proposto di dividersi una esigua somma di denaro rimasta disponibile nel fondo spese di rappresentanza. Le due si sarebbero incontrate poi in un bar di Cosenza dove la polizia piazz\u00f2 microspie per ascoltare la loro conversazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; E&#8217; stata condannata a tre anni di reclusione l\u2019ex prefetto di Cosenza, Paola Galeone, accusata di induzione indebita alla corruzione e rivelazione di segreti d\u2019ufficio. Riqualificata l\u2019imputazione in istigazione alla corruzione, l\u2019imputata \u00e8 stata assolta dall\u2019accusa di rivelazione di segreti d\u2019ufficio. Disposta inoltre, l\u2019interdizione perpetua dai pubblici uffici. Per l&#8217;accusa l&#8217;ex prefetto avrebbe [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":217982,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-244797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=244797"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/217982"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=244797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=244797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=244797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}