{"id":244855,"date":"2024-11-19T19:02:05","date_gmt":"2024-11-19T18:02:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=244855"},"modified":"2024-11-19T19:08:34","modified_gmt":"2024-11-19T18:08:34","slug":"sorgenti-ancora-a-secco-continua-la-riduzione-dellacqua-a-cosenza-rende-e-castrolibero","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sorgenti-ancora-a-secco-continua-la-riduzione-dellacqua-a-cosenza-rende-e-castrolibero\/","title":{"rendered":"Sorgenti ancora a secco: continua la riduzione dell&#8217;acqua a Cosenza, Rende e Castrolibero"},"content":{"rendered":"<p>COSENZA &#8211; Sorgenti ancora a secco e niente acqua nell&#8217;area urbana. Una settimana fa avevamo <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/sorgenti-a-secco-e-lacqua-sara-ridotta-a-rende-cosenza-castrolibero-montalto-e-in-altri-comuni-elenco\" target=\"_blank\" rel=\"noopener\">scritto<\/a> delle s<strong>orgenti a secco per la crisi idrica pesantissima<\/strong> che sta portando a continue<strong> interruzioni della fornitura idrica sull\u2019Acquedotto Abatemarco<\/strong> e, quindi, in diversi comuni dell\u2019area urbana in particolare a <strong>Cosenza, Rende e Castrolibero<\/strong>.<\/p>\n<h3>Sorgenti ancora ha secco: riduzione costante dell&#8217;acqua<\/h3>\n<p>Da una settimana la situazione non \u00e8 migliorata. Anzi, evidenzia Arpcal nella nota inviata a tutti i comuni interessati, <strong>la portata dell&#8217;acqua \u00e8 ridotta ed \u00e8 in atto un piano di ripartizione delle risorse idriche<\/strong> \u00abil perdurare di particolari condizioni di siccit\u00e0 che interessano l&#8217;attuale stagione &#8211; scrive Sorical -, s<strong>ta registrando, a seguito di monitoraggi giornalieri, una riduzione costante dell&#8217;acqua prodotta<\/strong> dal gruppo sorgentizio che alimenta lo scherma idrico dell&#8217;Abatemarco&#8221;.<\/p>\n<p><a href=\"http:\/\/www.sorical.it\" target=\"_blank\" rel=\"noopener\">Sorical,<\/a> in funzione alla risorsa idrica disponibile e alle verifiche eseguite lungo lo schema, \u00absta attuando<strong> un piano di ripartizione delle forniture, proporzionalmente alla riduzione delle sorgenti<\/strong> che vede <strong>sui centri principali che assorbono una maggiore portata, una riduzione in pi\u00f9 assoluto pi\u00f9 costante<\/strong>. Vista la risorsa idrica disponibile, si invitano le amministrazioni a utilizzare la funzione di accumulo e svuotamento delle vasche di accumulo a disposizione&#8221;.<\/p>\n<h3>Sorgenti a secco: tutte le zone e i quartieri interessati<\/h3>\n<p>Questi i comuni interessati dalla ripartizione delle forniture idriche: C<strong>osenza, Rende, Castrolibero, Rota Greca, San Bendetto Ullano<\/strong>. In particolare i maggiori disagi da diverse settimana si stanno registrando a <strong>Rende<\/strong> nei quartiere di Sant&#8217;Agostino, Saporito, Panicchio, Roges, Commenda, Santa Chiara, Santa Rosa, Arcavacata, Contrada Cutura, Santo Stefano, Contrada Rocchi, Contrada Chiodo, Contrada Dattoli, Contrada Monticello. Universit\u00e0, Zona Industriale, Quattromiglia, Villaggio Europa e zone limitrofe. Per quanto riguarda <strong>Castrolibero<\/strong>: Contrada Piani, Contrada Garofalo, Contrada Rusoli, Andreotta, Villaggio Evergreen e Contrada Marchesato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Sorgenti ancora a secco e niente acqua nell&#8217;area urbana. Una settimana fa avevamo scritto delle sorgenti a secco per la crisi idrica pesantissima che sta portando a continue interruzioni della fornitura idrica sull\u2019Acquedotto Abatemarco e, quindi, in diversi comuni dell\u2019area urbana in particolare a Cosenza, Rende e Castrolibero. Sorgenti ancora ha secco: riduzione [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":244856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-244855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=244855"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244855\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/244856"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=244855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=244855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=244855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}