{"id":244864,"date":"2024-11-19T19:59:02","date_gmt":"2024-11-19T18:59:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=244864"},"modified":"2024-11-19T20:01:46","modified_gmt":"2024-11-19T19:01:46","slug":"mandatoriccio-francesca-morta-nellincidente-sulla-tiburtina-la-salma-giungera-in-paese-questa-sera","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/mandatoriccio-francesca-morta-nellincidente-sulla-tiburtina-la-salma-giungera-in-paese-questa-sera\/","title":{"rendered":"Mandatoriccio, Francesca morta nell\u2019incidente sulla Tiburtina: la salma giunger\u00e0 in paese questa sera"},"content":{"rendered":"<div id=\"articolo\" class=\"uk-panel uk-margin\">\n<p>MANDATORICCIO &#8211;\u00a0 Prematura e tragica scomparsa della giovanissima<strong>\u00a0Francesca Mandarino,<\/strong>\u00a0la comunit\u00e0 accoglier\u00e0 l\u2019arrivo della salma questa sera, marted\u00ec 19, alle ore 20 all\u2019ingresso del paese, in prossimit\u00e0 della statua della Madonnina. \u00c8 quanto fa sapere il Sindaco Aldo Vincenzo Grispino che, ribadendo i sentimenti di grande commozione e di profonda vicinanza dell\u2019Amministrazione Comunale e dell\u2019intera cittadinanza alla famiglia e agli amici della studentessa deceduta a seguito di\u00a0<strong>un incidente stradale nella Capitale, invita i concittadini ad aderire al momento di preghiera.<\/strong><\/p>\n<p><strong>\u00a0<\/strong>In occasione delle esequie, che si terranno gioved\u00ec 21 novembre alle ore 15,30 nella chiesa dei Santi Pietro e Paolo, nel centro storico di Mandatoriccio \u00e8 stato proclamato il lutto cittadino. \u00c8 stata disposta la chiusura degli esercizi commerciali dalle ore 8 alle ore 18.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-244862 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Francesca-Mandarino_1.jpg\" alt=\"\" width=\"465\" height=\"299\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Francesca-Mandarino_1.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Francesca-Mandarino_1-300x193.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Francesca-Mandarino_1-768x495.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Francesca-Mandarino_1-652x420.jpg 652w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Francesca-Mandarino_1-150x97.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Francesca-Mandarino_1-696x448.jpg 696w\" sizes=\"auto, (max-width: 465px) 100vw, 465px\" \/><\/p>\n<h3>L&#8217;incidente<\/h3>\n<p>Lo schianto con l&#8217;altra automobile, lo sbalzo e la carambola contro un muro: cos\u00ec \u00e8 morta Francesca Mandarino, ventunenne di Cosenza che studiava come fuorisede a Roma, alla Sapienza e che presto avrebbe vissuto la sua prima tornata elettorale da candidata per le elezioni studentesche nelle liste di Sapienza Futura. Stava rientrando proprio da una cena di associazione, organizzata come momento di svago dalla compagna elettorale quando, in automobile con altri cinque ragazzi, c&#8217;\u00e8 stato il tragico incidente. La ragazza alla guida dell&#8217;Opel Mokka, una ventitreenne, \u00e8 stata denunciata per omicidio stradale dai vigili urbani: si attendono i risultati dell&#8217;alcool test<\/p>\n<\/div>\n<div class=\"ads_corriere ads_corriere-center ads_corriere-21\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>MANDATORICCIO &#8211;\u00a0 Prematura e tragica scomparsa della giovanissima\u00a0Francesca Mandarino,\u00a0la comunit\u00e0 accoglier\u00e0 l\u2019arrivo della salma questa sera, marted\u00ec 19, alle ore 20 all\u2019ingresso del paese, in prossimit\u00e0 della statua della Madonnina. \u00c8 quanto fa sapere il Sindaco Aldo Vincenzo Grispino che, ribadendo i sentimenti di grande commozione e di profonda vicinanza dell\u2019Amministrazione Comunale e dell\u2019intera cittadinanza [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":244863,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-244864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=244864"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244864\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/244863"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=244864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=244864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=244864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}