{"id":244913,"date":"2024-11-20T12:35:15","date_gmt":"2024-11-20T11:35:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=244913"},"modified":"2024-11-20T13:03:11","modified_gmt":"2024-11-20T12:03:11","slug":"schiavonea-arrestato-dopo-la-perquisizione-aveva-mezzo-chilo-di-droga-e-5-vasetti-di-benzocaina","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/schiavonea-arrestato-dopo-la-perquisizione-aveva-mezzo-chilo-di-droga-e-5-vasetti-di-benzocaina\/","title":{"rendered":"Schiavonea: arrestato dopo la perquisizione, aveva mezzo chilo di droga e 5 vasetti di benzocaina"},"content":{"rendered":"<p>CORIGLIANO ROSSANO (CS) &#8211; La squadra di Polizia Giudiziaria ha arrestato nell&#8217;area urbana di Corigliano, un <strong>uomo di 34 anni<\/strong>, per detenzione di sostanza stupefacente ai fini dello spaccio e per detenzione illegale di arma. Gli investigatori gi\u00e0 da qualche giorno erano sulle tracce del soggetto, su cui era pendente un ordine di esecuzione per la carcerazione emesso dalla Procura della Repubblica di Lecce, allo stato irreperibile.<\/p>\n<p>L&#8217;attivit\u00e0 investigativa ha consentito di individuare il <strong>domicilio del giovane<\/strong> presso uno <strong>stabile della frazione Schiavonea di Corigliano,<\/strong> all&#8217;interno del quale si era rifugiato per condurre una vita schiva e riservata. Originario del luogo infatti, da poco tempo si era ritirato a Corigliano Rossano dopo aver trascorso diversi anni fuori regione dove si era reso responsabile, tra l&#8217;altro, di alcuni <strong>reati contro la persona ed il patrimonio<\/strong> ed in ultimo <strong>in una citt\u00e0 del nord Italia<\/strong> dove aveva stabilito la propria residenza.<\/p>\n<p>Qualche giorno fa, dopo le attivit\u00e0 di osservazione dell&#8217;abitazione, gli agenti hanno sorpreso il giovane all&#8217;atto di uscire dal proprio appartamento. L&#8217;atteggiamento dell&#8217;indagato, <strong>insofferente al controllo<\/strong>, ha insospettito i poliziotti ma soprattutto il forte odore riconducibile alla presenza di <strong>sostanze stupefacenti<\/strong> proveniente dall&#8217;abitazione, ha determinato negli operatori la decisione di <strong>approfondire il controllo all&#8217;interno dei locali.<\/strong><\/p>\n<h4><strong>La perquisizione<\/strong><\/h4>\n<p>All&#8217;interno dell&#8217;abitazione sono stati trovato 10 panetti di hashish aventi peso complessivo pari a 541,25 grammi, 5 vasetti in vetro contenenti <strong>&#8220;benzocaina<\/strong>&#8220;, nonch\u00e9 2 bilancini di precisione digitale perfettamente funzionanti. Rinvenuta anche una carabina calibro 7,62mm, avente lunghezza 124 cm e potenza pari a 141 joules la cui detenzione \u00e8 vietata, per cui il giovane \u00e8 stato anche denunciato per detenzione illegale di arma. Il 34enne, \u00e8 stato tratto in arresto e associato alla Casa Circondariale di Castrovillari a disposizione dell&#8217;Autorit\u00e0 Giudiziaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO ROSSANO (CS) &#8211; La squadra di Polizia Giudiziaria ha arrestato nell&#8217;area urbana di Corigliano, un uomo di 34 anni, per detenzione di sostanza stupefacente ai fini dello spaccio e per detenzione illegale di arma. Gli investigatori gi\u00e0 da qualche giorno erano sulle tracce del soggetto, su cui era pendente un ordine di esecuzione per [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":179745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[19],"class_list":["post-244913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=244913"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/244913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/179745"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=244913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=244913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=244913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}