{"id":24501,"date":"2013-07-21T03:02:00","date_gmt":"2013-07-21T01:02:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=24501"},"modified":"2023-01-17T13:22:02","modified_gmt":"2023-01-17T12:22:02","slug":"9859-calabriasona-nelle-piazze-della-musica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9859-calabriasona-nelle-piazze-della-musica\/","title":{"rendered":"&#8220;Calabriasona&#8221; nelle Piazze della Musica"},"content":{"rendered":"<p>ROSSANO (CS) &#8211; Successo straordinario della seconda edizione delle Piazze Della Musica.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Migliaia di partecipanti, turisti e residenti di tutte le et\u00e0, intervenuti dal territorio, hanno letteralmente invaso il Centro storico, potendo fruire del patrimonio culturale e monumentale. Rilevante la presenza dei villeggianti che hanno raggiunto la Citt\u00e0 alta usufruendo delle navette gratuite. Piazza Steri, Matteotti,De Rosis, San Bartolomeo e&nbsp;Piazza San Marco, illuminate dagli scenografici e originali giochi di luce, hanno rivissuto al ritmo del <strong>sound popolare d\u2019autore<\/strong>, un connubio musicale di tradizione e identit\u00e0, ma con connotazioni attuali e giovanili.Soddisfatti il Sindaco Antoniotti e l\u2019assessore al turismo Caputo che ringraziano il presidente Scopelliti, per il suo interessamento affinch\u00e9 la Regione Calabria inserisse le Piazze della musica nel progetto Calabriasona, l\u2019Associazione Laboratorio giovani per il lavoro svolto nell\u2019organizzazione dell\u2019evento e lo sponsor ufficiale impresa LLPP di Naccarato.<\/p>\n<p>\u201cIl complessivo patrimonio identitario custodito nel centro storico \u2013 dichiarano il Sindaco e l\u2019assessore &#8211; se valorizzato e fatto fruire, pu\u00f2 trasformarsi nel pi\u00f9 efficace motore turistico di Rossano nel suo complesso. Intendiamo continuare a lavorare per la promozione di tutti i segmenti turistici ai quali Rossano, dalla montagna al mare, dal centro storico ai suoi prodotti, pu\u00f2 ambire. La Citt\u00e0 e il territorio hanno gradito palesemente questa iniziativa. Siamo soddisfatti \u2013 concludono &#8211; per il risultato anche di questa seconda edizione delle Piazze della musica. La formula scelta dall\u2019assessorato al turismo \u00e8 quella giusta e questa \u00e8 la strada che vogliamo e dobbiamo continuare a percorrere.\u201d Entusiasmante e coinvolgente il concerto di Mimmo Cavallaro, Cosimo Papandrea e i Taranproject,&nbsp;asse portante di Piazze della Musica 2013. Un evento quello dei pi\u00f9 celebri \u201ccantastorie\u201d calabresi, inserito nel pi\u00f9 ampioe prestigioso circuito di Calabriasona 2013, kermesse promossa dalla Regione Calabria, che ha fatto tappa in citt\u00e0 con tutta la sua carovana. E intanto proseguono gli appuntamenti inseriti nel cartellone estivo 2013. Rossano si prepara a vivere la seconda edizione dei Fuochi sull\u2019acqua, che si svolger\u00e0 domenica 21 luglio a partire dalle ore 22.00 sul Lungomare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROSSANO (CS) &#8211; Successo straordinario della seconda edizione delle Piazze Della Musica.<\/p>\n","protected":false},"author":22,"featured_media":24502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-24501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=24501"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24501\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/24502"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=24501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=24501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=24501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}