{"id":245022,"date":"2024-11-21T13:30:52","date_gmt":"2024-11-21T12:30:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=245022"},"modified":"2024-11-21T13:41:36","modified_gmt":"2024-11-21T12:41:36","slug":"stop-uso-selvaggio-dei-monopattini-anche-sulla-statale-107-solo-su-strade-urbane-con-targa-e-casco","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/stop-uso-selvaggio-dei-monopattini-anche-sulla-statale-107-solo-su-strade-urbane-con-targa-e-casco\/","title":{"rendered":"Stop all&#8217;uso selvaggio dei monopattini, anche sulla Statale 107: solo su strade urbane con targa e casco"},"content":{"rendered":"<p>COSENZA &#8211; arriva la stretta all&#8217;uso selvaggio dei monopattini.\u00a0Con l&#8217;approvazione ieri in Senato della<strong> riforma sul nuovo codice della strada<\/strong>, arriva una nuova stretta <strong>su uso di alcol e droga per chi si mette alla guida<\/strong>, ma anche <strong>sull&#8217;uso selvaggio <\/strong>dei monopattini in citt\u00e0 ma anche fuori dai centri abitati con l&#8217;introduzione della <a href=\"https:\/\/www.mit.gov.it\/\" target=\"_blank\" rel=\"noopener\">normativa<\/a> extra-codice, in particolare per la regolamentazione della micromobilit\u00e0. Ci riferiamo, in particolare,<strong> a quello che accade ogni giorno sia in citt\u00e0 ma anche lungo la Statale 107<\/strong> a Rende, come abbiamo pi\u00f9 volte segnalato<strong> dalla <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/la-segnalazione-a-rende-monopattini-sulla-statale-107-di-giorno-e-di-notte-possono-circolare\" target=\"_blank\" rel=\"noopener\">denuncia<\/a> di diversi cittadini<\/strong>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Monopattini-Rende3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-223280 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Monopattini-Rende3.jpg\" alt=\"\" width=\"484\" height=\"318\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Monopattini-Rende3.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Monopattini-Rende3-300x197.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Monopattini-Rende3-768x504.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Monopattini-Rende3-150x99.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Monopattini-Rende3-696x457.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Monopattini-Rende3-640x420.jpg 640w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Monopattini-Rende3-741x486.jpg 741w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/a><\/p>\n<p>Giorno e notte, con il sole o la pioggia, <strong>nel tratto compreso tra Santo Stefano, Arcavacata a Contrada Cutura<\/strong>, decine di cittadini extracomunitari, che lavorano in un negozio gestito da cinesi sotto il Campus, <strong>raggiugono il loro posto di lavoro a bordo di monopattini, quasi sempre senza indicatori luminosi<\/strong>, immettendosi sulla Statale dalle traverse laterali come fossero comuni auto, circolando anche la notte spesso senza luci e <strong>percorrendo una strada a loro vietata<\/strong>. Per di pi\u00f9 non \u00e8 raro vederli in due su un solo monopattino.<\/p>\n<h3>Nuove regole contro l&#8217;uso selvaggio dei monopattini<\/h3>\n<p>In base alle nuove regole approvate ieri in Senato, <strong>la circolazione sar\u00e0 consentita solo su strade urbane con limite di velocit\u00e0 non superiore a 50 km\/h<\/strong> <strong>e non su piste ciclabili o aree pedonali tantomeno lungo le Statali<\/strong>. Le aziende che forniscono servizi di sharing dovranno installare <strong>sistemi automatici per impedire il funzionamento dei mezzi al di fuori delle aree consentite<\/strong>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/monopattini-cosenza-comune-01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-141738 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/monopattini-cosenza-comune-01.jpg\" alt=\"\" width=\"523\" height=\"299\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/monopattini-cosenza-comune-01.jpg 900w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/monopattini-cosenza-comune-01-300x172.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/monopattini-cosenza-comune-01-768x439.jpg 768w\" sizes=\"auto, (max-width: 523px) 100vw, 523px\" \/><\/a><\/p>\n<p>I conducenti<strong> dovranno portare il casco ed essere assicurati per la responsabilit\u00e0 civile<\/strong>. I monopattini dovranno essere muniti di i<strong>ndicatori luminosi di svolta e freno, ma anche di una targa di riconoscimento<\/strong>. In mancanza di documenti, <strong>la multa va da 100 a 400 euro mentre<\/strong> per la mancanze delle frecce previste multe tra 200 e 800 euro.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; arriva la stretta all&#8217;uso selvaggio dei monopattini.\u00a0Con l&#8217;approvazione ieri in Senato della riforma sul nuovo codice della strada, arriva una nuova stretta su uso di alcol e droga per chi si mette alla guida, ma anche sull&#8217;uso selvaggio dei monopattini in citt\u00e0 ma anche fuori dai centri abitati con l&#8217;introduzione della normativa extra-codice, [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":245033,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[19],"class_list":["post-245022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/245022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=245022"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/245022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/245033"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=245022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=245022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=245022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}