{"id":245037,"date":"2024-11-21T14:43:49","date_gmt":"2024-11-21T13:43:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=245037"},"modified":"2024-11-21T14:51:04","modified_gmt":"2024-11-21T13:51:04","slug":"niente-acqua-a-cosenza-rende-e-nellarea-urbana-maltempo-provoca-problemi-allabatemarco","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/niente-acqua-a-cosenza-rende-e-nellarea-urbana-maltempo-provoca-problemi-allabatemarco\/","title":{"rendered":"Niente acqua a Cosenza, Rende e nell&#8217;area urbana: maltempo provoca problemi all&#8217;Abatemarco"},"content":{"rendered":"<p>COSENZA &#8211; Non bastava il problema legato alla siccit\u00e0 e alle <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/sorgenti-ancora-a-secco-continua-la-riduzione-dellacqua-a-cosenza-rende-e-castrolibero\" target=\"_blank\" rel=\"noopener\">sorgenti<\/a> dell&#8217;Abatemarco a secco che stanno portando da settimane a una riduzione idrica. <strong>A causa del<a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/tempesta-di-vento-sfiorata-la-tragedia-a-cosenza-per-la-caduta-di-un-semaforo-danni-a-camigliatello-foto\" target=\"_blank\" rel=\"noopener\"> maltempo<\/a><\/strong>, che da due giorni sta imperversando sulla Calabria, si stanno registrando oggi dei<strong> disservizi nell&#8217;erogazione idropotabile a Cosenza, Rende, Castrolibero, Rota greca e Cerzeto,<\/strong> a causa di urgenti lavori sulla rete idrica provocati da un guasto. In particolare si registrano disservizi nella distribuzione dell&#8217;acqua per il<strong>\u00a0fermo dell&#8217;apparecchiatura elettromeccanica<\/strong> dell&#8217;<strong>impianto di sollevamento Nascejume<\/strong> nel comune di San Donato di Ninea e provocato delle <strong>avverse condizioni atmosferiche<\/strong> in atto nella zona.<\/p>\n<p>Sorical evidenzia che \u00ab<strong>il personale ha ripristinato il normale funzionamento dell&#8217;impianto<\/strong> ma il problema potrebbe ripresentarsi, con c<strong>onseguente interruzione dell&#8217;acqua sollevata<\/strong> a integrazione dello schema idrico e far registrate <strong>una riduzione della fornitura idropotabile a tutte le utenze servite<\/strong>\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Non bastava il problema legato alla siccit\u00e0 e alle sorgenti dell&#8217;Abatemarco a secco che stanno portando da settimane a una riduzione idrica. A causa del maltempo, che da due giorni sta imperversando sulla Calabria, si stanno registrando oggi dei disservizi nell&#8217;erogazione idropotabile a Cosenza, Rende, Castrolibero, Rota greca e Cerzeto, a causa di [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":191837,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-245037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/245037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=245037"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/245037\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/191837"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=245037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=245037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=245037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}