{"id":24517,"date":"2013-07-22T05:30:31","date_gmt":"2013-07-22T03:30:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=24517"},"modified":"2023-01-17T13:22:03","modified_gmt":"2023-01-17T12:22:03","slug":"9867-a3-nuove-aperture-tratti-di-altomonte-morano-calabro-e-lagonegro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9867-a3-nuove-aperture-tratti-di-altomonte-morano-calabro-e-lagonegro\/","title":{"rendered":"Il ministro taglia il nastro della &#8216;nuova&#8217; Salerno &#8211; Reggio Calabria"},"content":{"rendered":"<p style=\"text-align: justify;\">COSENZA &#8211; Alla presenza del Ministro delle Infrastrutture e dei Trasporti,<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Maurizio Lupi, l&#8217;Anas ha inaugurato stamane sull&#8217;autostrada A3 Salerno-Reggio Calabria il nuovo tratto di 10 chilometri compreso tra gli svincoli di Campotenese e Morano Calabro, e, sempre nel cosentino, \u00e8 stato riaperto al traffico il tratto autostradale di 2,6 km tra Firmo e Altomonte, posto immediatamente a sud dello svincolo di Firmo\/Sibari e, infine, un nuovo tratto di 4 km tra Lagonegro Sud e Lauria Nord, in Basilicata, per un totale di quasi 17 km di nuova autostrada. L&#8217;inaugurazione del tratto compreso tra gli svincoli di Campotenese e Morano Calabro avviene con un anno e mezzo di anticipo rispetto al tempo contrattuale previsto.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&#8220;Bisogna dare atto al Ministro dei Trasporti e delle Infrastrutture Maurizio Lupi di questo suo viaggio in Calabria, che e&#8217; un segno d&#8217;attenzione verso il nostro territorio. Ne approfitto per sottoporgli qualche problematica. Una, che e&#8217; piu&#8217; di costume, e che riguarda l&#8217;uso invalso negli ultimi anni nella nostra regione di tagliare nastri anche in presenza di opere minimali&#8221;. Lo afferma in una nota l&#8217;ex governatore della Calabria, Agazio Loiero, il quale aggiunge: &#8220;Ci affidiamo alla concretezza di Lupi per segnalare alla sua sensibilita&#8217; di Ministro quelle opere che sapevamo in itinere nella passata amministrazione, opere progettate in passato, che noi abbiamo per alcuni lotti cofinanziato e fortemente spinto per loro esecuzione nel 2006 alla presenza dell&#8217;allora Ministro Di Pietro&#8221;. &#8220;E&#8217; il caso della trasversale delle Serre &#8211; sostiene Loiero &#8211; che per noi e&#8217; importante quanto e forse piu&#8217; del rifacimento dell&#8217;Autostrada, insieme alle condizioni in cui versa la 106. A questo proposito, si veda il tratto definitivamente aperto, di cui in questi giorni s&#8217;accorgono gli utenti che possono arrivare, diversamente dal passato, in un batter occhio da Simeri Crichi a Copanello. Un&#8217;opera che sembrava un puntiglio voluto dell&#8217;amministrazione della passata legislatura, che ha risolto tanti problemi di questo territorio. L&#8217;Anas, soprattutto Ciucci, deve farsi carico di tematiche di questo genere, che in Calabria sono molto diffuse e non sono grandi problemi. A riguardo approfittiamo della presenza del Ministro per segnalare lo svincolo di S. Eufemia d&#8217;Aspromonte, una problematica che forse per l&#8217;Anas non significa nulla, ma che e&#8217; essenziale per i paesi che insistono in quel pezzo di Calabria. Infine, e&#8217; inutile ricordare al Ministro che il Ponte sullo stretto &#8211; conclude Agazio Loiero &#8211; sia in presenza della crisi sia un contesto gerarchico delle priorita&#8217;, e&#8217; un&#8217;opera completamente priva di senso&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Alla presenza del Ministro delle Infrastrutture e dei Trasporti,<\/p>\n","protected":false},"author":22,"featured_media":24518,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-24517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=24517"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24517\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/24518"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=24517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=24517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=24517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}