{"id":245309,"date":"2024-11-25T10:57:14","date_gmt":"2024-11-25T09:57:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=245309"},"modified":"2024-11-25T10:57:14","modified_gmt":"2024-11-25T09:57:14","slug":"cosenza-giovane-mamma-si-risveglia-dal-coma-finalmente-dopo-2-mesi-tiene-in-braccio-la-sua-bimba","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-giovane-mamma-si-risveglia-dal-coma-finalmente-dopo-2-mesi-tiene-in-braccio-la-sua-bimba\/","title":{"rendered":"Cosenza, giovane mamma si risveglia dal coma: finalmente dopo 2 mesi tiene in braccio la sua bimba"},"content":{"rendered":"<p class=\"v1MsoNormal\">COSENZA \u2013 <strong>Un dolce abbraccio ha scritto la parola fine in fondo a una storia davvero emozionante<\/strong>. \u00c8 accaduto nei giorni scorsi presso la sede operativa Madonna della Catena iGreco Ospedali Riuniti,<strong> dove una giovane mamma, da poco uscita dal coma e in fase di riabilitazione, ha potuto tenere di nuovo tra le braccia la sua bambina<\/strong>. Dopo il parto in ospedale, la donna aveva avuto un grave problema neurologico, che l&#8217;aveva costretta al ricovero.<strong> La gioia della nascita di una nuova vita aveva, cos\u00ec, lasciato il posto alla preoccupazione.<\/strong><\/p>\n<p class=\"v1MsoNormal\">Ma questa \u00e8 una storia di speranza. &#8220;La nascita di una nuova vita \u00e8 uno dei momenti pi\u00f9 belli e magici che si possa immaginare&#8221;, spiega la dottoressa Carmelina Magar\u00f2, psicologa e psicoterapeuta iGreco Ospedali Riuniti. &#8220;A dominare questo periodo sono i pianti del bambino, la mancanza di sonno e molto altro.<strong> Ma sempre tutto contornato da tanta felicit\u00e0. Accade per\u00f2, che una mamma, dopo il parto, abbia un danno neurologico grave.<\/strong> I medici comunicano che \u00e8 in coma. Una mamma e una bambina alle quali \u00e8 impedito di vivere insieme. Ma niente \u00e8 perduto. La famiglia \u00e8 presente, ci crede, prega e spera che si possa svegliare e riabbracciare la sua piccola&#8221;.Ed \u00e8 proprio quel che \u00e8 accaduto.<\/p>\n<p class=\"v1MsoNormal\">Dopo due mesi dal parto, la giovane mamma \u00e8 arrivata alla Sede operativa Madonna della Catena iGreco Ospedali Riuniti in fase di risveglio, ma ancora non del tutto fuori dal coma. Ha iniziato il percorso di recupero a fatica, ha lottato per poter tenere in braccio di nuovo sua figlia. <strong>&#8220;Le lacrime hanno preso il sopravvento e l&#8217;emozione di tutti \u00e8 stata contagiosa quando la dolce paziente \u00e8 riuscita a raggiungere il traguardo, inseguito con tanta determinazione<\/strong>. La riabilitazione \u00e8 anche questo&#8221;, conclude la dottoressa Magar\u00f2.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA \u2013 Un dolce abbraccio ha scritto la parola fine in fondo a una storia davvero emozionante. \u00c8 accaduto nei giorni scorsi presso la sede operativa Madonna della Catena iGreco Ospedali Riuniti, dove una giovane mamma, da poco uscita dal coma e in fase di riabilitazione, ha potuto tenere di nuovo tra le braccia la [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":245310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-245309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/245309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=245309"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/245309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/245310"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=245309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=245309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=245309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}