{"id":245445,"date":"2024-11-27T09:00:21","date_gmt":"2024-11-27T08:00:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=245445"},"modified":"2024-11-26T20:04:26","modified_gmt":"2024-11-26T19:04:26","slug":"rende-nuove-opportunita-per-vecchi-problemi-due-giorni-dedicati-alla-cardiologia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/rende-nuove-opportunita-per-vecchi-problemi-due-giorni-dedicati-alla-cardiologia\/","title":{"rendered":"Rende: &#8220;nuove opportunit\u00e0 per vecchi problemi&#8221;, due giorni dedicati alla cardiologia"},"content":{"rendered":"<p>RENDE &#8211; &#8220;Nuove opportunit\u00e0 per vecchi problemi&#8221; intorno all&#8217;ipertensione arteriosa, all&#8217;ischemia miocardica, e ancora scompenso e fibrillazione atriale. Questi gli argomenti di discussione di un importante congresso cardiologico in programma venerd\u00ec e sabato prossimi a Rende, a villa Fabiano. Responsabile scientifico \u00e8 il dottor <strong>Francesco Fontana<\/strong>. Presidente del convegno il Prof. Antonio Curcio. L&#8217;evento, organizzato dal provider Xenia di Francesca Mazza, \u00e8 stato accreditato su Agenas ed \u00e8 valido ai fini dell&#8217;ottenimento dei crediti formativi Ecm.<\/p>\n<p>&#8220;L&#8217;impatto clinico quotidiano supportato da indagini strumentali e le scelte che dobbiamo optare spesso creano incertezze sebbene le evidenze scientifiche debbano costituire la base delle decisioni&#8221;, si legge nel razionale scientifico. L&#8217;esperienza dimostra che la difficolt\u00e0 di trasferire le prove alle attivit\u00e0 assistenziali, &#8220;incostante ricerca dell&#8217;appropriatezza, la divergenza tra ci\u00f2 che si conosce e quello che si applica, sono alcune tra le ragioni che spiegano perch\u00e9 non si seguono le &#8220;<strong>Linee Guida e le Raccomandazioni<\/strong>&#8220;. Vi sono situazioni, invece, secondo gli organizzatori, nelle quali &#8220;mancano del tutto indicazioni, oppure, quando ci sono, non risultano trasferibili a quel contesto o a quel paziente e comunque vanno prese delle decisioni&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-245447 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Screenshot_20241126_091626_WhatsApp.jpg\" alt=\"\" width=\"454\" height=\"462\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Screenshot_20241126_091626_WhatsApp.jpg 1079w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Screenshot_20241126_091626_WhatsApp-295x300.jpg 295w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Screenshot_20241126_091626_WhatsApp-1006x1024.jpg 1006w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Screenshot_20241126_091626_WhatsApp-768x782.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Screenshot_20241126_091626_WhatsApp-413x420.jpg 413w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Screenshot_20241126_091626_WhatsApp-150x153.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Screenshot_20241126_091626_WhatsApp-300x305.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Screenshot_20241126_091626_WhatsApp-696x708.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/11\/Screenshot_20241126_091626_WhatsApp-1068x1087.jpg 1068w\" sizes=\"auto, (max-width: 454px) 100vw, 454px\" \/><\/p>\n<p>Il congresso si propone di affrontare aspetti dibattuti e controversi di importanti argomenti cardiologici quali l&#8217;ipertensione arteriosa, la sindrome coronarica acuta, l&#8217;ischemia miocardica cronica, lo scompenso e la fibrillazione atriale, &#8220;allo scopo di mettere a confronto esperienze e contesti clinici per delineare e condividere protocolli di cura pi\u00f9 appropriati e una condivisione multidisciplinare&#8221;. <strong>Notizia importante<\/strong>: \u00e8 il primo congresso <strong>dell&#8217;Azienda Ospedaliera Annunziata di Cosenza con l&#8217;Unical<\/strong>. Nel corso del convegno, infatti, ci sar\u00e0 la presenza degli specializzandi in malattie dell&#8217;apparato cardiovascolare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; &#8220;Nuove opportunit\u00e0 per vecchi problemi&#8221; intorno all&#8217;ipertensione arteriosa, all&#8217;ischemia miocardica, e ancora scompenso e fibrillazione atriale. Questi gli argomenti di discussione di un importante congresso cardiologico in programma venerd\u00ec e sabato prossimi a Rende, a villa Fabiano. Responsabile scientifico \u00e8 il dottor Francesco Fontana. Presidente del convegno il Prof. Antonio Curcio. L&#8217;evento, organizzato [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":245446,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-245445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/245445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=245445"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/245445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/245446"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=245445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=245445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=245445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}