{"id":245480,"date":"2024-11-26T19:50:05","date_gmt":"2024-11-26T18:50:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=245480"},"modified":"2024-11-26T19:50:05","modified_gmt":"2024-11-26T18:50:05","slug":"paura-a-scala-coeli-incendio-divampa-in-un-edificio-antico-salvato-un-anziano-di-92-anni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/paura-a-scala-coeli-incendio-divampa-in-un-edificio-antico-salvato-un-anziano-di-92-anni\/","title":{"rendered":"Paura a Scala Coeli: incendio divampa in un edificio antico, salvato un anziano di 92 anni"},"content":{"rendered":"<p>SCALA COELI (CS) &#8211; Il rogo si \u00e8 verificato nel borgo antico e le fiamme sono divampate la scorsa notte nella <strong>zona di via Piazzetta,<\/strong> nei pressi della Chiesa Matrice. Le fiamme hanno interessato un&#8217;antica abitazione che un tempo ospitava un asilo gestitio dalle suore. Secondo quanto si \u00e8 appreso <strong>le fiamme sarebbero partite da un locale sottostante<\/strong>, adiacente all\u2019immobile, utilizzato per lo stoccaggio di <strong>legna secca<\/strong>.<\/p>\n<p>L&#8217;incendio si propagato in poco tempo ed ha avvolto le travi di legno mettendo in pericolo le abitazioni circostanti, alcune delle quali sono costruzioni storiche. Allertati i vigili del fuoco sono partite le operazioni di spegnimento nel corso delle quali, <strong>un uomo di 92 anni, invalido e costretto su una sedia a rotelle<\/strong> \u00e8 stato tratto in salvo, fortunatamente senza riportare danni, grazie anche alla prontezza della badante. Poi \u00e8 stato affidato ai familiari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SCALA COELI (CS) &#8211; Il rogo si \u00e8 verificato nel borgo antico e le fiamme sono divampate la scorsa notte nella zona di via Piazzetta, nei pressi della Chiesa Matrice. Le fiamme hanno interessato un&#8217;antica abitazione che un tempo ospitava un asilo gestitio dalle suore. Secondo quanto si \u00e8 appreso le fiamme sarebbero partite da [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":196743,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-245480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/245480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=245480"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/245480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/196743"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=245480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=245480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=245480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}