{"id":24567,"date":"2013-07-23T08:15:37","date_gmt":"2013-07-23T06:15:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=24567"},"modified":"2023-01-17T13:22:05","modified_gmt":"2023-01-17T12:22:05","slug":"9893-via-simonetta-a-vincere-sono-i-residenti-il-cantiere-sara-rimosso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9893-via-simonetta-a-vincere-sono-i-residenti-il-cantiere-sara-rimosso\/","title":{"rendered":"Via Simonetta, a vincere sono i residenti: il cantiere sar\u00e0 rimosso"},"content":{"rendered":"<p>COSENZA \u2013 Il Tar d\u00e0 ragione al Comune.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">La \u2018L. F. Costruzioni di Mirabelli Fulvio &amp; Co.\u2019 dovr\u00e0 pagare le spese per riportare via Simonetta allo stato originario. Le fondamenta poste dall\u2019impresa edile avvalendosi di un\u2019autorizzazione rilasciata <span>dal commissario ad acta nominato dal Dirigente generale del dipartimento Urbanistica e Territorio della Regione Calabria<\/span>nonostante il \u2018silenzio-diniego\u2019 del Comune di Cosenza saranno rimosse. A nulla sono serviti i ricorsi che i titolari della Mirabelli &amp; Co. Hanno presentato al Consiglio di Stato e al Tar. Tutto rigettato. L\u2019azienda non pu\u00f2 costruire in via Simonetta. Il progetto non possiede i requisiti necessari. A denunciarlo, da subito, furono i residenti. Un intero condominio confinante con il cantiere della Mirabelli &amp; Co. si oppose all\u2019edificazione della struttura dando vita ad una querelle che va avanti sin dai tempi di Perugini, dal 2006. Da allora l\u2019azienda dopo aver ricevuto la revoca della concessione edilizia dalla stessa Regione perch\u00e9 illegittima avrebbe raccolto i propri attrezzi abbandonando il cantiere in pieno centro. Una situazione che dopo anni ha fatto crescere l\u2019insofferenza dei residenti che hanno provveduto ad esporre costantemente le proprie lamentele sia in Comune sia in Procura. Ieri il successo dell\u2019ufficio legale del Comune di Cosenza rappresentato dall\u2019avvocato Agostino Rosselli ha dato ragione ai cosentini. La L.F. Costruzioni di Mirabelli Fulvio &amp; Co. non pu\u00f2 costruire. Anzi. Deve provvedere a ripulire tutto. Un diktat che da tempo viene disertato dall\u2019azienda. Ad eseguire la bonifica di via Simonetta, per ora, provveder\u00e0 il Comune a proprie spese. A fine lavori presenter\u00e0 il conto all\u2019impresa edile che dovr\u00e0 pagare per i danni arrecati al quartiere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA \u2013 Il Tar d\u00e0 ragione al Comune.<\/p>\n","protected":false},"author":22,"featured_media":24568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-24567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=24567"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/24568"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=24567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=24567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=24567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}