{"id":24583,"date":"2013-07-23T12:34:21","date_gmt":"2013-07-23T10:34:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=24583"},"modified":"2023-01-17T13:22:07","modified_gmt":"2023-01-17T12:22:07","slug":"9901-costringe-una-bambina-ad-un-rapporto-orale-e-si-scopre-che-e-la-sorellastra","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9901-costringe-una-bambina-ad-un-rapporto-orale-e-si-scopre-che-e-la-sorellastra\/","title":{"rendered":"Costringe una bambina ad un rapporto orale e si scopre che e\u2019 la sorellastra"},"content":{"rendered":"<p style=\"text-align: justify;\">Pavia &#8211; Questa e\u2019 la brutta storia di un orco<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">di 32 anni e di una bambina di soli nove, per di piu\u2019 sua sorellastra.<\/p>\n<p style=\"text-align: justify;\">Accade a Pavia: i due erano andati al parco per fare una passeggiata quando un poliziotto libero dal servizio e fortunatamente sul posto a fare jogging, intravede i due nascosti e nudi. Il pavese 32enne stava tentando di costringere la bambina ad avere un rapporto orale. Questa la scena a cui assiste il poliziotto, conclusasi con la scoperta della presenza del testimone da parte dell\u2019aggressore che velocemente si riveste e si allontana dalla bimba, tentando di fuggire. Il poliziotto riesce a bloccare la fuga dell\u2019orco, che tenta di difendersi fino all&#8217;ultimo negando il suo stato di aggressore pedofilo, lo arresta e lo porta in Questura. Solo qui emergera\u2019 come assurda aggravante il rapporto di parentela tra i due fratellastri. Il giovane ora si trova in carcere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pavia &#8211; Questa e\u2019 la brutta storia di un orco<\/p>\n","protected":false},"author":22,"featured_media":24584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-24583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=24583"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/24584"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=24583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=24583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=24583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}