{"id":245985,"date":"2024-12-15T07:30:00","date_gmt":"2024-12-15T06:30:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=245985"},"modified":"2024-12-11T12:46:23","modified_gmt":"2024-12-11T11:46:23","slug":"scuola-iscrizioni-alla-prima-classe-per-lanno-2025-2026-domande-dall8-al-31-gennaio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/scuola-iscrizioni-alla-prima-classe-per-lanno-2025-2026-domande-dall8-al-31-gennaio\/","title":{"rendered":"Scuola, iscrizioni alla prima classe per l&#8217;anno 2025-2026: domande dall\u20198 al 31 gennaio"},"content":{"rendered":"<p>COSENZA &#8211; Ripartono le<strong> iscrizioni alle scuole dell&#8217;infanzia e al primo e secondo ciclo di istruzione per l&#8217;anno scolastico 2025\/2026<\/strong>. La finestra temporale per la presentazione delle domande <strong>va dall&#8217;8 al 31 gennaio 2025<\/strong>. I genitori potranno presentare le domande esclusivamente online tramite la<a href=\"https:\/\/unica.istruzione.gov.it\/it\/orientamento\/iscrizioni\" target=\"_blank\" rel=\"noopener\"> piattaforma Unica<\/a> per tutte le classi iniziali della Scuola primaria, secondaria di primo grado e secondaria di secondo grado statale.\u00a0<strong>Online anche le iscrizioni ai percorsi di istruzione e formazione professionale e alle scuole paritarie<\/strong> che su base volontaria aderiscono alla modalit\u00e0 telematica.<\/p>\n<h3>iscrizioni alle scuole dell&#8217;infanzia sulla piattaforma unica<\/h3>\n<p>Alla piattaforma Unica si accede attraverso le credenziali <strong>Spid (Sistema Pubblico di Identit\u00e0 Digitale), Cie (Carta di identit\u00e0 elettronica), Cns (Carta Nazionale dei Servizi) o eidas (electronic IDentification Authentication and Signature)<\/strong>. Nelle scuole dell\u2019infanzia, per le quali pu\u00f2 essere presentata un\u2019unica domanda cartacea, resta l\u2019indicazione di attivare, da parte degli Uffici di ambito territoriale, d\u2019intesa con le Amministrazioni comunali interessate, opportune misure di coordinamento tra le scuole statali e le scuole paritarie che gestiscono il servizio sul territorio, per equilibrare il pi\u00f9 possibile il rapporto domanda-offerta<strong>. L\u2019eventuale impossibilit\u00e0 di accoglimento delle domande deve essere comunicata agli interessati, tempestivamente e con adeguata motivazione, al fine di consentire l\u2019opzione verso altra scuola<\/strong>.\u00a0Restano cartacee, e quindi vanno consegnate direttamente presso la Segreteria delle Istituzioni scolastiche, le domande di iscrizione alla Scuola dell&#8217;infanzia, alle scuole di Valle d&#8217;Aosta, Trento e Bolzano, nonch\u00e9 le iscrizioni a specifici percorsi dettagliati nell&#8217;annuale nota emanata dal Ministero dell&#8217;Istruzione e del Merito.<\/p>\n<p><strong>Escluse dal sistema di iscrizione online<\/strong> anche l\u2019istruzione per gli adulti (oggetto di successiva comunicazione), le classi terze dei licei artistici, il percorso di specializzazione per \u201cEnotecnico\u201d degli istituti tecnici del settore tecnologico a indirizzo \u201cAgraria, agroalimentare e agroindustria\u201d, articolazione \u201cViticoltura ed enologia\u201d, gli alunni\/studenti in fase di preadozione, per i quali l\u2019iscrizione \u00e8 effettuata dalla famiglia affidataria direttamente presso l\u2019istituzione scolastica prescelta. <strong>Nella piattaforma Unica sono disponibili informazioni sulle scuole (&#8220;Cerca la tua scuola&#8221;) e sezioni dedicate all&#8217;orientamento,<\/strong> per accompagnare le famiglie e gli studenti nella scelta della scuola pi\u00f9 adatta alle loro competenze, aspirazioni e attitudini. Per accedere alla piattaforma Unica, sar\u00e0 necessario utilizzare le credenziali SPID (Sistema Pubblico di Identit\u00e0 Digitale), CIE (Carta d\u2019identit\u00e0 elettronica), CNS (Carta Nazionale dei Servizi) o eIDAS (electronic IDentification Authentication and Signature).<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/05\/Scuola-di-religione-concorso.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-231478 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/05\/Scuola-di-religione-concorso.jpg\" alt=\"Scuola di religione concorso\" width=\"565\" height=\"348\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/05\/Scuola-di-religione-concorso.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/05\/Scuola-di-religione-concorso-300x185.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/05\/Scuola-di-religione-concorso-768x473.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/05\/Scuola-di-religione-concorso-681x420.jpg 681w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/05\/Scuola-di-religione-concorso-150x92.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/05\/Scuola-di-religione-concorso-696x429.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/05\/Scuola-di-religione-concorso-356x220.jpg 356w\" sizes=\"auto, (max-width: 565px) 100vw, 565px\" \/><\/a><\/p>\n<h3>Istituzioni scolastiche coinvolte<\/h3>\n<p>Per le s<strong>cuole paritarie e i percorsi IeFP,<\/strong> siano essi erogati da Istituti professionali e\/o Centri di formazione accreditati dalle Regioni, occorre verificarne l\u2019adesione alla modalit\u00e0 telematica. La facolt\u00e0 di avvalersi o non avvalersi dell\u2019insegnamento della religione cattolica si esercita all\u2019atto dell\u2019iscrizione nella classe prima, mediante l\u2019apposita sezione online. Tale scelta ha valore per l\u2019intero corso di studi, fatto salvo il diritto soggettivo di operare una modifica a partire dall\u2019anno scolastico successivo. A<strong>lle opzioni, per chi non intende seguire lo specifico insegnamento, si accede tramite un\u2019apposita funzionalit\u00e0 del sistema \u201cIscrizioni online\u201d tra il 31 maggio e il 1\u00b0 luglio 2025 utilizzando le credenziali di identit\u00e0 digitale<\/strong>.<\/p>\n<p><strong>Per le scuole primarie e secondarie \u00e8 possibile indicare in subordine alla scuola di prima scelta altre due opzioni<\/strong>; l\u2019ultima scuola che tratta la domanda di iscrizione, qualora sia impossibilitata ad accoglierla in quanto eccedente rispetto ai posti rimasti disponibili, \u00e8 tenuta, con il supporto dell\u2019Ufficio di ambito territoriale, ad affiancare la famiglia nell\u2019individuazione di una diversa istituzione scolastica idonea e ad accertarsi che il procedimento si concluda con l\u2019effettiva iscrizione dell\u2019alunno\/studente. <strong>Tale responsabilit\u00e0 ricade in capo alle scuole e agli Uffici di ambito territoriale<\/strong> anche in caso di impossibilit\u00e0 di accoglimento, per mancata disponibilit\u00e0 di posti, di richieste effettuate in corso d\u2019anno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Ripartono le iscrizioni alle scuole dell&#8217;infanzia e al primo e secondo ciclo di istruzione per l&#8217;anno scolastico 2025\/2026. La finestra temporale per la presentazione delle domande va dall&#8217;8 al 31 gennaio 2025. I genitori potranno presentare le domande esclusivamente online tramite la piattaforma Unica per tutte le classi iniziali della Scuola primaria, secondaria [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":245430,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-245985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/245985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=245985"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/245985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/245430"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=245985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=245985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=245985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}