{"id":246179,"date":"2024-12-05T07:49:53","date_gmt":"2024-12-05T06:49:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=246179"},"modified":"2024-12-05T11:49:11","modified_gmt":"2024-12-05T10:49:11","slug":"ndrangheta-e-scambio-elettorale-politico-mafioso-33-misure-cautelari-arrestata-anche-una-suora","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ndrangheta-e-scambio-elettorale-politico-mafioso-33-misure-cautelari-arrestata-anche-una-suora\/","title":{"rendered":"&#8216;Ndrangheta e scambio elettorale politico mafioso: 33 misure cautelari. Arrestata anche una suora"},"content":{"rendered":"<p>BRESCIA &#8211; Polizia di Stato e Guardia di Finanza, coordinati dalla Direzione Distrettuale Antimafia della Procura di Brescia, stanno eseguendo dalle prime ore di oggi, <strong>35 misure cautelari ed il sequestro preventivo di beni per oltre 1,8 milioni di euro. <\/strong>Numerose le perquisizioni scattate nelle province di Brescia, <strong>Reggio Calabria,<\/strong> Milano, Como, Lecco, Varese, Verona, Viterbo e Treviso, in relazione <strong>ad un&#8217;associazione mafiosa di matrice &#8216;ndranghetista operativa in territorio bresciano,<\/strong>\u00a0dedita alla commissione di <strong>estorsioni<\/strong>, <strong>traffico di armi e droga<\/strong>, <strong>ricettazioni<\/strong>, <strong>usura<\/strong>, <strong>reati tributari e riciclaggio<\/strong>. Gli investigatori hanno contestato il reato di scambio elettorale politico mafioso.<\/p>\n<p>La complessa indagine, coordinata dalla Procura della Repubblica di Brescia &#8211; Direzione Distrettuale Antimafia e partita<strong> a settembre 2020<\/strong>, ha riguardato l\u2019operativit\u00e0 di un gruppo di \u2018ndrangheta, originario di<strong> Sant\u2019Eufemia d\u2019Aspromonte<\/strong>\u00a0e residente da anni in questa provincia e legata da<strong> rapporti federativi<\/strong> <strong>alla cosca \u201cAlvaro\u201d,<\/strong> <strong>egemone nella zona aspromontana<\/strong> compresa tra i comuni di Sinopoli e Sant\u2019Eufemia d\u2019Aspromonte.<\/p>\n<div style=\"width: 740px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-246179-1\" width=\"740\" height=\"419\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/Brescia-Operazione-DDA-contro-la-ndrangheta.mp4?_=1\" \/><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/Brescia-Operazione-DDA-contro-la-ndrangheta.mp4\">https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/Brescia-Operazione-DDA-contro-la-ndrangheta.mp4<\/a><\/video><\/div>\n<h3>Associazione per delinquere di matrice \u2018ndranghetista<\/h3>\n<p>Contestualmente i Carabinieri del Comando Provinciale di Brescia e dei reparti dell\u2019Arma territorialmente competenti hanno dato esecuzione ad un<strong>\u2019ulteriore misura cautelare sempre nell\u2019ambito del medesimo procedimento penale, nei confronti di 8 indagati,<\/strong> tra i quali anche membri della sopra citata <strong>associazione per delinquere di matrice \u2018ndranghetista,<\/strong> ritenuti a vario titolo presunti responsabili dei reati di detenzione illegale di armi, riciclaggio, usura e ricettazione, aggravati dal metodo mafioso, oltre al reato di detenzione ai fini di spaccio di sostanze stupefacenti.<\/p>\n<h3>Una locale di &#8216;ndrangheta a Brescia<\/h3>\n<p>Facendo leva sulla forza di intimidazione che deriva dal vincolo associativo, il gruppo avrebbe r<strong>iprodotto, in territorio bresciano, una \u201clocale\u201d in grado di porre in essere le peculiari azioni che caratterizzano le associazioni di tipo mafioso<\/strong>, quali estorsioni, traffico di armi e stupefacenti, ricettazioni, usura e scambio elettorale politico-mafioso. In particolare, nel corso delle indagini sono emersi <strong>i legami e le cointeressenze tra il gruppo investigato e altri gruppi criminali sempre di matrice \u2018ndranghetista presenti nell\u2019hinterland bresciano<\/strong>, tra i quali si sarebbe instaurato un rapporto di mutua assistenza finalizzato alla realizzazione di una moltitudine di condotte illecite.<\/p>\n<p>Sono stati altres\u00ec documentati i<strong> legami tra il sodalizio mafioso e un soggetto con esposizione pubblica<\/strong>, attivo nella comunit\u00e0 bresciana, con il quale il sodalizio avrebbe intrattenuto rapporti caratterizzati dal tipico pactum sceleris dello scambio elettorale politico-mafioso, ovvero l\u2019impegno per il sostegno elettorale del clan con la futura promessa di reciproci illeciti vantaggi economici.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/ndrangheta-brescia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-246198\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/ndrangheta-brescia.jpg\" alt=\"ndrangheta brescia\" width=\"970\" height=\"600\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/ndrangheta-brescia.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/ndrangheta-brescia-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/ndrangheta-brescia-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/ndrangheta-brescia-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/ndrangheta-brescia-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/ndrangheta-brescia-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/ndrangheta-brescia-356x220.jpg 356w\" sizes=\"auto, (max-width: 970px) 100vw, 970px\" \/><\/a><\/p>\n<h3>Tra gli arresti anche una suora &#8220;a disposizione&#8221; del sodalizio<\/h3>\n<p>Tra le persone arrestate ci sono <strong>l&#8217;ex consigliere comunale di Brescia in quota Fratelli d&#8217;Italia Giovanni Acri<\/strong>, finito ai domiciliari, e una religiosa, <strong>suor Anna Donelli<\/strong>, <strong>ritenuta &#8220;a disposizione del sodalizio<\/strong> <strong>per garantire il collegamento con i sodali detenuti in carcere&#8221;. P<\/strong>i\u00f9 volte, avrebbe svolto il ruolo di <strong>intermediario, tra gli associati e soggetti in detenzione<\/strong>, approfittando dell\u2019incarico spirituale che le consentiva di avere libero accesso alle strutture penitenziarie. Ai domiciliari anche <strong>Mauro Galeazzi, ex esponente della Lega nel Comune di Castel Mella<\/strong>, nel Bresciano, arrestato in passato per tangenti e poi a scarcerato e assolto.<\/p>\n<h3>Il medico che curava gli &#8216;ndranghetisti feriti<\/h3>\n<p>Secondo gli inquirenti della Procura antimafia di Brescia l&#8217;ex consigliere comunale di Brescia in quota Fratelli d&#8217;Italia Giovanni Acri, arrestato e ai domiciliari nell&#8217;ambito di un&#8217;inchiesta per presunte infiltrazioni della &#8216;ndrangheta nel Bresciano, si sarebbe messo a disposizione del gruppo &#8216;ndranghetista guidato dai Tripodi nella veste di medico quale \u00e8 &#8220;anche in occasione di <strong>ferimenti degli appartenenti al sodalizio e<\/strong> <strong>dei loro complici<\/strong> durante l`esecuzione di reati&#8221;.<\/p>\n<h3>Sequestrati quasi 2 milioni di euro<\/h3>\n<p>Parallelamente, il gruppo investigato avrebbe dimostrato di essere in grado di far evolvere le proprie dinamiche economiche, assumendo tutte le caratteristiche delle moderne organizzazioni criminali che operano nel Nord Italia, <strong>abbinando ai reati di tipo tradizionale, anche delitti di natura economico-finanziaria<\/strong>. A\u00a0carico dei soggetti indagati sono stati emessi provvedimenti di s<strong>equestro preventivo, finalizzati alla confisca per equivalente, per un importo complessivo pari a oltre 1.800.000 euro,<\/strong> quale provento delle condotte penal-tributarie e riciclatorie ipotizzate.\u00a0So<strong>no attualmente in corso molteplici perquisizioni a cura di 300 appartenenti alle tre Forze di Polizi<\/strong>a, estese anche nelle province di Bergamo, Verona e Treviso, condotte con il supporto di moderni mezzi tecnici del Servizio Centrale Operativo della Polizia di Stato, del Servizio Centrale I.C.O. della Guardia di Finanza e dell\u2019Arma dei Carabinieri nonch\u00e9 delle unit\u00e0 cinofile &#8211; per la ricerca di armi e droga &#8211; e \u201ccash dog\u201d &#8211; per la ricerca di contanti, in una cornice di sicurezza garantita anche dall\u2019impiego di personale delle U.O.P.I. della Polizia di Stato e di militari specializzati A.T.- P.I. della Guardia di Finanza e dell\u2019Aliquota di Primo Intervento dei Carabinieri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BRESCIA &#8211; Polizia di Stato e Guardia di Finanza, coordinati dalla Direzione Distrettuale Antimafia della Procura di Brescia, stanno eseguendo dalle prime ore di oggi, 35 misure cautelari ed il sequestro preventivo di beni per oltre 1,8 milioni di euro. Numerose le perquisizioni scattate nelle province di Brescia, Reggio Calabria, Milano, Como, Lecco, Varese, Verona, [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":246195,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-246179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/246179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=246179"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/246179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/246195"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=246179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=246179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=246179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}