{"id":24673,"date":"2013-07-25T13:00:10","date_gmt":"2013-07-25T11:00:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=24673"},"modified":"2023-01-17T13:22:12","modified_gmt":"2023-01-17T12:22:12","slug":"9949-venticinquenne-vola-dal-quarto-piano-muore-schiantandosi-al-suolo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9949-venticinquenne-vola-dal-quarto-piano-muore-schiantandosi-al-suolo\/","title":{"rendered":"Vola dal quarto piano, muore schiantandosi al suolo"},"content":{"rendered":"<p>COSENZA &#8211; Tragedia nelle notti estive di Cassano.<\/p>\n<p>  <!--more-->  <\/p>\n<p class=\"data_articolo data\" style=\"text-align: justify;\">Una giovane di 25 anni, Valentina Cioca, di nazionalit\u00e0 rumena, \u00e8 morta cadendo da un appartamento al quarto piano, dove abitava con alcuni connazionali. Il fatto \u00e8 avvenuto nella notte a Cassano Jonio. Inutili i soccorsi del 118. I carabinieri, accorsi sul posto, pensano che si sia trattato di un incidente. La procura di Castrovillari ha disposto comunque l&#8217;autopsia. Al momento l&#8217;ipotesi degli investigatori \u00e8 che si sia trattato di un incidente. Le indagini, comunque, proseguono ed il sostituto procuratore della Repubblica di Castrovillari, Maria Grazia Anastasia, ha disposto l&#8217;autopsia.Una ragazza di 25 anni, La giovane lavorava come bracciante agricola nelle campagne della sibaritide.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Tragedia nelle notti estive di Cassano.<\/p>\n","protected":false},"author":22,"featured_media":24674,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-24673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=24673"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/24674"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=24673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=24673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=24673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}