{"id":247015,"date":"2024-12-15T08:58:36","date_gmt":"2024-12-15T07:58:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=247015"},"modified":"2024-12-15T09:00:42","modified_gmt":"2024-12-15T08:00:42","slug":"per-alvini-nessun-caso-camporese-fa-parte-del-progetto-non-gioca-sono-scelte-e-si-accettano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/per-alvini-nessun-caso-camporese-fa-parte-del-progetto-non-gioca-sono-scelte-e-si-accettano\/","title":{"rendered":"Per Alvini nessun caso Camporese: \u00abfa parte del progetto. Non gioca? Sono scelte e si accettano\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; <strong>Nessun caso Camporese<\/strong>. Parola del tecnico Massimiliano Alvini che nel dopogara di <a href=\"https:\/\/quicosenza.it\/news\/sport\/cosenza-errori-e-difesa-ballerina-il-cesena-ringrazia-e-vince-2-a-1-camporese-ora-e-un-caso\" target=\"_blank\" rel=\"noopener\">Cesena-Cosenza<\/a>, a specifica domanda in sala stampa, con un lapidario commenta evidenzia come<strong> il difensore pisano non stia giocando esclusivamente per scelta tecnica <\/strong>e non \u00e8 fuori dal progetto Cosenza.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/Camporese.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-247018 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/Camporese.jpg\" alt=\"Camporese\" width=\"449\" height=\"289\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/Camporese.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/Camporese-300x193.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/Camporese-768x495.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/Camporese-652x420.jpg 652w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/Camporese-150x97.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/12\/Camporese-696x448.jpg 696w\" sizes=\"auto, (max-width: 449px) 100vw, 449px\" \/><\/a><\/p>\n<p>Certo \u00e8 che dopo aver iniziato la stagione da titolare, anche a causa dell&#8217;infortunio al ginocchio e la contemporanea crescita di Dalle Mura, <strong>il centrale non mette piede sul terreno di gioco da oltre due mesi e mezzo<\/strong> neanche da subentrato. \u00ab<em>Camporese fa parte del progetto Cosenza. <strong>Le scelte si accettano<\/strong>, siamo 25 giocatori, in questo momento le scelte sono altre e<strong> andiamo in altre direzioni<\/strong>. \u00c8 una scelta stop! <strong>Altrimenti\u00a0Camporese non era qua<\/strong><\/em>\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Nessun caso Camporese. Parola del tecnico Massimiliano Alvini che nel dopogara di Cesena-Cosenza, a specifica domanda in sala stampa, con un lapidario commenta evidenzia come il difensore pisano non stia giocando esclusivamente per scelta tecnica e non \u00e8 fuori dal progetto Cosenza. Certo \u00e8 che dopo aver iniziato la stagione da titolare, anche [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":247017,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[19],"class_list":["post-247015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=247015"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247015\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/247017"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=247015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=247015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=247015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}