{"id":247051,"date":"2024-12-15T18:00:24","date_gmt":"2024-12-15T17:00:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=247051"},"modified":"2024-12-15T16:22:21","modified_gmt":"2024-12-15T15:22:21","slug":"seconde-case-e-locali-commerciali-domani-ultimo-giorno-per-pagare-il-saldo-imu","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/seconde-case-e-locali-commerciali-domani-ultimo-giorno-per-pagare-il-saldo-imu\/","title":{"rendered":"Seconde case e locali commerciali: domani ultimo giorno per pagare il saldo Imu"},"content":{"rendered":"<p>COSENA &#8211; <strong>Una rata media di 511 euro per le seconde case e fino a 3000 euro per quelle di lusso nelle grandi citt\u00e0<\/strong>. Per i proprietari di immobili d<strong>omani, luned\u00ec 16 dicembre, \u00e8 l&#8217;ultimo giorno per pagare la seconda tranche dell&#8217;Imu<\/strong>, l&#8217;imposta che assicura alle casse pubbliche un gettito, fra acconto di giugno e saldo finale, di circa 22 miliardi di euro. Il<strong> versamento della prima rata era dovuto infatti entro il 16 giugn<\/strong>o applicando per i primi sei mesi del 2024 le aliquote stabilite dai Comuni per il 2023.<strong> La seconda rata va a saldo dell&#8217;imposta<\/strong> dovuta per l&#8217;intero anno con eventuale conguaglio sulla prima rata corrisposta. <strong>Per pagare \u00e8 possibile utilizzare l&#8217;F24<\/strong>, utilizzando i codici tributo o, in alternativa, con il bollettino, messo a disposizione da Poste italianepresso tutte le proprie agenzie, che riporta il numero di conto corrente 1008857615, valido indistintamente per quasi tutti i Comuni del territorio nazionale, intestato a &#8220;Pagamento Imu&#8221;.<\/p>\n<h3>IMU per Confedilizia imposta onerosa e iniqua<\/h3>\n<p>Per la Confedilizia si tratta di &#8220;<strong>un&#8217;imposta onerosa e iniqua<\/strong>, una patrimoniale che sempre pi\u00f9 frequentemente <strong>colpisce soggetti che, oltre a non trarre alcun frutto dal loro bene, non hanno pi\u00f9 neanche un reddito da lavoro<\/strong> dal quale ricavare le risorse per pagare questa vera e propria &#8216;patrimoniale diffusa&#8217;.&#8221; L&#8217;associazione sostiene che si tratta di &#8220;<strong>un tributo che punisce il risparmio e danneggia l&#8217;economia<\/strong>. Si potrebbe iniziare eliminando l&#8217;IMU sulle case date in affitto con i contratti &#8216;a canone concordato&#8217;, per estendere l&#8217;offerta abitativa, e sugli immobili dei piccoli centri, per agevolare la rinascita di borghi e aree interne. Sulla scelta delle priorit\u00e0 si pu\u00f2 ragionare, ma anzitutto serve la volont\u00e0 politica&#8221;. Dai calcoli del Servizio Politiche Economiche, Fiscali e Previdenziali della Uil &#8220;p<strong>er l&#8217;abitazione principale considerata di lusso (categorie catastali A\/1, A\/8, A\/9), il costo medio complessivo dell&#8217;Imu sar\u00e0 di 2.531 euro<\/strong> (1.266 euro per l&#8217;acconto di giugno), <strong>con punte di oltre 6.000 euro nelle grandi citt\u00e0<\/strong>.<\/p>\n<p><strong>Il costo medio complessivo dell&#8217;Imu per una &#8220;seconda casa&#8221;, ubicata in una citt\u00e0 capoluogo, sar\u00e0 di 1.022 euro<\/strong> (511 euro per l&#8217;acconto di giugno), con p<strong>unte di oltre 2.000 euro nelle grandi citt\u00e0<\/strong>. Le pertinenze dell&#8217;abitazione principale di lusso, come cantine, garage, posti auto e tettoie (classificate nelle categorie catastali C2, C6, C7), sono soggette a Imu con la stessa aliquota applicata alle prime case di lusso. Il costo medio annuo per queste pertinenze \u00e8 di 99 euro (circa 50 euro per l&#8217;acconto di giugno).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENA &#8211; Una rata media di 511 euro per le seconde case e fino a 3000 euro per quelle di lusso nelle grandi citt\u00e0. Per i proprietari di immobili domani, luned\u00ec 16 dicembre, \u00e8 l&#8217;ultimo giorno per pagare la seconda tranche dell&#8217;Imu, l&#8217;imposta che assicura alle casse pubbliche un gettito, fra acconto di giugno e [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":247052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-247051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=247051"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/247052"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=247051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=247051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=247051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}