{"id":247190,"date":"2024-12-17T09:59:01","date_gmt":"2024-12-17T08:59:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=247190"},"modified":"2024-12-17T09:59:17","modified_gmt":"2024-12-17T08:59:17","slug":"celebrata-dallarcidiocesi-di-rossano-cariati-la-giornata-dellinclusion-day","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/celebrata-dallarcidiocesi-di-rossano-cariati-la-giornata-dellinclusion-day\/","title":{"rendered":"Celebrata dall\u2019Arcidiocesi di Rossano Cariati la giornata dell&#8217;Inclusion day"},"content":{"rendered":"<p>CORIGLIANO ROSSANO &#8211;\u00a0 Una giornata ricca di attivit\u00e0 dedicate all&#8217;inclusione per evidenziare il valore di ogni persona indipendentemente dalle sue fragilit\u00e0. Stiamo parlando dell\u2019<strong>Inclusion day<\/strong>, celebrata dall\u2019<strong>Arcidiocesi di Rossano Cariati<\/strong> in favore delle persone con disabilit\u00e0.<\/p>\n<p>Una iniziativa che ha coinvolto l&#8217;IIS Luigi Palma \u2013 ITI ITG Green Falcone e Borsellino. Due i momenti che hanno caratterizzato la giornata: la mattina presso l\u2019 IIS Palma \u2013ITI ITG Green Falcone e Borsellino di Corigliano, dopo i saluti di <strong>S. E. l&#8217;Arcivescovo monsignor Maurizio Aloise e della dirigente scolastica Cinzia D&#8217;Amico<\/strong>, si sono svolti una serie di eventi, con dei momenti di riflessioni, \u00a0attraverso testimonianze di sportivi e figure di spicco, tra questi tramite collegamento Daniele Lavia campione del mondo, europeo e italiano di pallavolo e Max Manfredi atleta paralimpico. Nel pomeriggio le parrocchie del comune di Corigliano Rossano si sono ritrovate all\u2019oratorio del Salesiani per un momento di riflessione e di confronto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO ROSSANO &#8211;\u00a0 Una giornata ricca di attivit\u00e0 dedicate all&#8217;inclusione per evidenziare il valore di ogni persona indipendentemente dalle sue fragilit\u00e0. Stiamo parlando dell\u2019Inclusion day, celebrata dall\u2019Arcidiocesi di Rossano Cariati in favore delle persone con disabilit\u00e0. Una iniziativa che ha coinvolto l&#8217;IIS Luigi Palma \u2013 ITI ITG Green Falcone e Borsellino. Due i momenti che [&hellip;]<\/p>\n","protected":false},"author":66,"featured_media":247191,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[19,135],"class_list":["post-247190","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-ionio","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=247190"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/247191"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=247190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=247190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=247190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}