{"id":247218,"date":"2024-12-17T13:52:32","date_gmt":"2024-12-17T12:52:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=247218"},"modified":"2024-12-17T13:53:23","modified_gmt":"2024-12-17T12:53:23","slug":"tentano-di-estorcere-denaro-ad-un-imprenditore-turistico-tre-misure-cautelari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/tentano-di-estorcere-denaro-ad-un-imprenditore-turistico-tre-misure-cautelari\/","title":{"rendered":"Tentano di estorcere denaro ad un imprenditore turistico, tre misure cautelari"},"content":{"rendered":"<p>ISOLA DI CAPO RIZZUTO (KR) &#8211; Tre persone tutte appartanenti allo stesso nucleo familiare sono stati raggiunti da altrettante misure cautelari eseguite dai carabinieri della Tenenza di Isola Capo Rizzuto. In particolare un <strong>62enne \u00e8 stato arrestato e condotto in carcere<\/strong> mentre agli altri due soggetti, di <strong>54 e 35 anni<\/strong>, \u00e8 stato imposto il divieto di dimora nel comune di Isola Capo Rizzuto.<\/p>\n<p>Secondo l&#8217;accusa avrebbero pi\u00f9 volte minacciato un imprenditore turistico per impedirgli di svolgere la propria attivit\u00e0 e a <strong>corrispondere parte dei suoi guadagni, per evitare ulteriori conseguenze per lui e per la sua famiglia.\u00a0<\/strong><\/p>\n<p>L&#8217;indagine dei militari \u00e8 scattata dopo la <strong>denuncia dell&#8217;imprenditore<\/strong> attivo nel settore turistico e ricettivo, pi\u00f9 volte oggetto di minacce e inviti, anche in presenza di altre persone, a non esercitare pi\u00f9 la sua attivit\u00e0. L&#8217;uomo, al quale era stato anche intimato di versare parte dei suoi guadagni, in una circostanza era stato anche aggredito fisicamente.<br \/>\nL&#8217;attivit\u00e0 investigativa svolta dai militari ha permesso di effettuare riscontri trali da fare emergere le condotte estorsive da parte di ciascuno dei tre soggetti raggiunti dall&#8217;ordinanza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ISOLA DI CAPO RIZZUTO (KR) &#8211; Tre persone tutte appartanenti allo stesso nucleo familiare sono stati raggiunti da altrettante misure cautelari eseguite dai carabinieri della Tenenza di Isola Capo Rizzuto. In particolare un 62enne \u00e8 stato arrestato e condotto in carcere mentre agli altri due soggetti, di 54 e 35 anni, \u00e8 stato imposto il [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":240795,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-247218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=247218"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247218\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/240795"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=247218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=247218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=247218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}