{"id":247238,"date":"2024-12-28T22:00:41","date_gmt":"2024-12-28T21:00:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=247238"},"modified":"2024-12-28T18:51:38","modified_gmt":"2024-12-28T17:51:38","slug":"italiani-bocciati-negli-stili-di-vita-si-esagera-con-fumo-e-alcol-preoccupa-il-sovrappeso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/italiani-bocciati-negli-stili-di-vita-si-esagera-con-fumo-e-alcol-preoccupa-il-sovrappeso\/","title":{"rendered":"Italiani bocciati negli stili di vita: si esagera con fumo e alcol, preoccupa il sovrappeso"},"content":{"rendered":"<p>ROMA &#8211;<strong> Quasi met\u00e0 della popolazione italiana \u00e8 in sovrappeso o obesa, 1 persona su 6 esagera con l&#8217;alcol e 1 su 5 fum<\/strong>a. Segnali di allarme arrivano anche dai pi\u00f9 giovani, con un terzo dei bambini con meno di 10 anni che ha un peso eccessivo e 1 adolescente su 30 che consuma alcolici con una certa regolarit\u00e0. Sono alcuni dei dati che emergono dall&#8217;<strong>indagine Istat<\/strong> &#8216;Aspetti della vita quotidiana&#8217; che mostra come sugli stili di vita, in Italia, ci sia ancora molto da fare. La rilevazione, che si riferisce al 2023, mostra come<strong> \u00e8 fumatore il 18,7% della popolazione con pi\u00f9 di 11 anni<\/strong> (era il 19% nel 2022) <strong>e il 3,5% fuma pi\u00f9 di 20 sigarette<\/strong>. L&#8217;abitudine al fumo continua a essere pi\u00f9 diffusa tra gli uomini che tra le donne (22,3% contro 15,2%), tuttavia nel tempo la forbice si sta assottigliando, per la contrazione dell&#8217;attitudine al fumo tra gli uomini a fronte di una relativa stabilit\u00e0 del dato tra le donne. Il fumo tende inoltre a essere pi\u00f9 frequente tra i pi\u00f9 giovani, con un picco tra le persone di 25-34 anni (26,9%).<\/p>\n<p><strong>Sono 8 milioni le persone che consumano abitualmente una quantit\u00e0 eccessiva di bevande alcoliche<\/strong> o che riportano di essersi ubriacate. Tra gli uomini la quota \u00e8 pari al 21,2% mentre tra le donne \u00e8 pari al 9,2%. Tra le fasce di et\u00e0, attenzione meritano gli over-65 e giovanissimi. Per i primi, il superamento delle quantit\u00e0 raccomandate avviene con il consumo abituale di vino soprattutto durante il pasto (ci\u00f2 si verifica per il 54,6% degli uomini e il 64,6% delle donne). Per i secondi, che non dovrebbero consumare affatto alcol, il 15,7% tra gli 11 i 17 anni ha bevuto almeno una bevanda alcolica nell&#8217;anno e il 2,8% ha un consumo settimanale, se non giornaliero, o l&#8217;abitudine al binge drinking.<\/p>\n<p><strong>Trend negativo per quanto riguarda il peso in eccesso<\/strong>. Nel 2023 il 46,3% delle persone di 18 anni e pi\u00f9 \u00e8 in eccesso di peso: tra queste il 34,6% \u00e8 in sovrappeso e l&#8217;11,8% in condizione di obesit\u00e0. Il dato, nel complesso, \u00e8 stabile rispetto all&#8217;anno precedente. Tuttavia, nell&#8217;ultimo anno \u00e8 aumentata la quota relativa dell&#8217;obesit\u00e0 rispetto al sovrappeso. Preoccupa il sovrappeso nei minori. Nel biennio 2022-2023 pi\u00f9 di un ragazzo su quattro in et\u00e0 compresa tra e 3 e 17 anni (il 26,7%) \u00e8 in eccesso di peso. La percentuale raggiunge per\u00f2 il 33% nella fascia 3-10 anni.<\/p>\n<p><strong>Segnali di lieve miglioramento per quel che riguarda l&#8217;attitudine a svolgere attivit\u00e0 fisica<\/strong>: nel 2023 \u00e8 pari al 35% la quota di persone di 3 anni e pi\u00f9 sedentarie, con un calo di 2,2 punti rispetto all&#8217;anno precedente e di sei punti rispetto a 10 anni prima.<br \/>\nPer quanto riguarda in particolare le donne, dalla relazione al Parlamento appena pubblicata sulle azioni di promozione e di sostegno della Medicina di Genere a cura del ministero della Salute, emerge una maggiore presenza di malattie croniche e di sofferenza psichica. In particolare, nel sesso femminile si registrano 149,6 casi per 1.000 di una malattia cronica grave rispetto ai 144,7 casi per 1.000. La differenza si amplia se si guarda alla presenza di due o pi\u00f9 malattie croniche: ne soffrono 244 donne per 1.000 contro 170 uomini. <strong>In positivo, le donne sembrano vincenti sul fronte degli stili di vita<\/strong>: gli uomini infatti mostrano tassi pi\u00f9 elevati di mortalit\u00e0 evitabile (21,7 per 10.000 abitanti contro 11,6). In particolare, lo svantaggio maschile \u00e8 soprattutto spiegato dalla componente &#8220;prevenibile&#8221;, ossia quella maggiormente legata agli stili di vita. Per la mortalit\u00e0 prevenibile il valore degli uomini \u00e8, infatti, pari a 14,9 per 10 mila, mentre per le donne \u00e8 pari a 5,6, poco pi\u00f9 di un terzo di quella maschile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Quasi met\u00e0 della popolazione italiana \u00e8 in sovrappeso o obesa, 1 persona su 6 esagera con l&#8217;alcol e 1 su 5 fuma. Segnali di allarme arrivano anche dai pi\u00f9 giovani, con un terzo dei bambini con meno di 10 anni che ha un peso eccessivo e 1 adolescente su 30 che consuma alcolici [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":247239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-247238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=247238"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/247239"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=247238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=247238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=247238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}