{"id":247336,"date":"2024-12-18T18:05:27","date_gmt":"2024-12-18T17:05:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=247336"},"modified":"2024-12-18T19:15:06","modified_gmt":"2024-12-18T18:15:06","slug":"morte-ilaria-mirabelli-alla-guida-dellauto-cera-mario-molinari-lo-stabiliscono-i-periti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/morte-ilaria-mirabelli-alla-guida-dellauto-cera-mario-molinari-lo-stabiliscono-i-periti\/","title":{"rendered":"Morte Ilaria Mirabelli, alla guida dell&#8217;auto c&#8217;era Mario Molinari: lo stabiliscono i periti"},"content":{"rendered":"<p>COSENZA &#8211; C&#8217;\u00e8 una svolta nelle indagini per la morte di<strong> Ilaria Mirabelli,<\/strong> la 38enne cosentina<strong> <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/tragico-incidente-in-sila-domani-i-funerali-di-ilaria-dinamica-ancora-da-chiarire\" target=\"_blank\" rel=\"noopener\">morta a Lorica<\/a>\u00a0il 25 agosto scorso<\/strong> in un presunto incidente stradale sulla statale 108 bis Silana-Cariati. <strong>Secondo le tre perizie tecniche depositate in Procura a Cosenza<\/strong> tutte e tre le risultanze convergono in una sola direzione:<strong> alla guida dell&#8217;auto, la Volkswagen Up, c&#8217;era Mario Molinari <\/strong>che \u00e8 indagato con l&#8217;accusa di omicidio stradale.<\/p>\n<p>L&#8217;uomo e compagno della vittima,<strong><a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/morte-di-ilaria-mirabelli-mario-molinari-e-indagato-per-omicidio-stradale\" target=\"_blank\" rel=\"noopener\"> indagato per omicidio stradale<\/a><\/strong> dopo la denuncia querela della famiglia di Ilaria, per tramite del legale Guido Siciliano,<strong> ha sempre negato di essere alla guida dell&#8217;auto quel tragico giorno<\/strong>. Ora la palla passa alla Procura della repubblica di Cosenza che dovr\u00e0 pronunciarsi alla luce dei risultati dei periti. Perizia che, sulla base della <strong>ricostruzione effettuata insieme alla sorella di Ilaria<\/strong>, per il legale della famiglia &#8220;aveva da subito dimostrato <strong>la quasi impossibilit\u00e0 che una persona con la corporatura della vittima potesse guidare l&#8217;automobile in questione con il sedile nella posizione in cui \u00e9 stato trovato&#8221;<\/strong>. L&#8217;accertamento era stato disposto dalla Procura della Repubblica con la\u00a0 sorella di Ilaria che si era seduta alla guida dell&#8217;auto coinvolta nell&#8217;incidente. L&#8217;indagine sul decesso di Ilaria Mirabelli \u00e8 coordinata dalla PM Donatella Donato e dalla collega Mariangela Farro.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/ilaria-mirabelli-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-239172 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/ilaria-mirabelli-2.jpg\" alt=\"Ilaria Mirabelli\" width=\"550\" height=\"340\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/ilaria-mirabelli-2.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/ilaria-mirabelli-2-300x185.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/ilaria-mirabelli-2-768x474.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/ilaria-mirabelli-2-680x420.jpg 680w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/ilaria-mirabelli-2-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/ilaria-mirabelli-2-696x430.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/ilaria-mirabelli-2-356x220.jpg 356w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a><\/p>\n<h3>L&#8217;incidente in cui mor\u00ec Ilaria Mirabelli<\/h3>\n<p>Ilaria Mirabelli mor\u00ec a seguito dell&#8217;incidente avvenuto in <strong>localit\u00e0 Baracchelle<\/strong> <strong>nei pressi di Lorica<\/strong> tra le 16:30 e le ore 17:00 di domenica 25 agosto, dopo che la coppia aveva pranzato in Sila insieme ad un\u2019altra coppia. L\u2019incidente avvenuto sulla strada statale 108 bis aveva per\u00f2 sollevato sin da subito una serie di dubbi, a cominciare <strong>proprio su chi stesse guidando poco prima che la Volkswagen Up finisse fuori strada<\/strong>. Il corpo di Ilaria venne trovato a<strong> circa 50 metri di distanza<\/strong>. Da pi\u00f9 parti, nei giorni immediatamente successivi al decesso della donna, erano giunti da diverse componenti della societ\u00e0 civile cosentina appelli e richieste per fare piena luce sulla vicenda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; C&#8217;\u00e8 una svolta nelle indagini per la morte di Ilaria Mirabelli, la 38enne cosentina morta a Lorica\u00a0il 25 agosto scorso in un presunto incidente stradale sulla statale 108 bis Silana-Cariati. Secondo le tre perizie tecniche depositate in Procura a Cosenza tutte e tre le risultanze convergono in una sola direzione: alla guida dell&#8217;auto, [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":239039,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-247336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=247336"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/239039"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=247336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=247336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=247336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}