{"id":24759,"date":"2013-07-29T10:32:27","date_gmt":"2013-07-29T08:32:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=24759"},"modified":"2023-01-17T13:22:17","modified_gmt":"2023-01-17T12:22:17","slug":"9997-acquascooter-in-corsa-tra-i-bagnanti-mezzo-sequestrato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9997-acquascooter-in-corsa-tra-i-bagnanti-mezzo-sequestrato\/","title":{"rendered":"Acquascooter in corsa tra i bagnanti, mezzo sequestrato"},"content":{"rendered":"<p>CROTONE &#8211; Un&#8217;impennata tra le onde e la moto d&#8217;acqua finisce sotto sequestro.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">La Capitaneria di porto di Crotone e&#8217; intervenuta nel tratto di costa compreso tra S. Leonardo e Steccato di Cutro, a seguito delle diverse segnalazioni provenienti da turisti e bagnanti riguardanti l&#8217;utilizzo degli acquascooter in prossimita&#8217; delle zone di mare riservate alla balneazione. Nel corso dei controlli si e&#8217; proceduto al fermo di un acquascooter il cui conducente oltre a navigare nella fascia di mare riservata alla balneazione e&#8217; risultato privo della patente nautica. L&#8217;acquascooter e&#8217; stato pertanto posto sotto sequestro. A carico del conducente, oltre alla contestazione della navigazione a motore nella fascia riservata alla balneazione e&#8217; stata irrogata la multa di 2754 euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; Un&#8217;impennata tra le onde e la moto d&#8217;acqua finisce sotto sequestro.<\/p>\n","protected":false},"author":22,"featured_media":24760,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-24759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=24759"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/24760"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=24759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=24759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=24759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}