{"id":247926,"date":"2024-12-29T10:01:09","date_gmt":"2024-12-29T09:01:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=247926"},"modified":"2024-12-29T10:17:04","modified_gmt":"2024-12-29T09:17:04","slug":"dipignano-celebra-il-natale-con-il-concerto-della-banda-f-r-aiello","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/dipignano-celebra-il-natale-con-il-concerto-della-banda-f-r-aiello\/","title":{"rendered":"Dipignano celebra il Natale con il concerto della Banda &#8220;F.R. Aiello&#8221;"},"content":{"rendered":"<p>DIPIGNANO (CS) \u2013 Un\u2019atmosfera magica ha avvolto la <strong>Chiesa di San Nicola<\/strong> sabato 28 dicembre, in occasione del tradizionale Concerto di Natale 2024 eseguito dalla <strong>Banda Citt\u00e0 di Dipignano 1994 &#8220;F.R. Aiello&#8221;<\/strong>. L\u2019evento, che ha visto una partecipazione calorosa da parte della comunit\u00e0, si \u00e8 trasformato in un momento di grande condivisione e bellezza musicale.<\/p>\n<p>Fondata nel 1994, la banda rappresenta una realt\u00e0 storica di grande rilevanza per il territorio, non solo per l\u2019eccellenza musicale, ma anche per la capacit\u00e0 di tramandare i valori della cultura e della tradizione. Il 2024 ha segnato l traguardo dei 30 anni di attivit\u00e0, un anniversario importante che promette di essere celebrato degnamente.<\/p>\n<p>Anche il <strong>sindaco di Dipignano<\/strong>, Gaetano Sorcale, presente all\u2019evento, ha voluto sottolineare l\u2019importanza della banda, definendola &#8220;un patrimonio culturale e umano che d\u00e0 valore al tempo&#8221;. Il primo cittadino ha annunciato il pieno supporto dell\u2019amministrazione comunale per l\u2019organizzazione di un grande evento che festeggi questo prestigioso anniversario.<\/p>\n<p>La Banda &#8220;F.R. Aiello&#8221; si conferma, ancora una volta, non solo custode delle tradizioni musicali, ma anche un pilastro della vita sociale di Dipignano, capace di unire generazioni diverse sotto il segno della musica.<\/p>\n<p>Un plauso va ai musicisti e al direttore, che con passione e dedizione continuano a scrivere una storia di successo e orgoglio per tutta la comunit\u00e0. La serata, dedicata alla grandiosit\u00e0 dell&#8217;opera lirica, ha lasciato un ricordo indelebile nei cuori dei presenti, dimostrando che la musica, come il tempo, sa rendere eterno ogni momento.<\/p>\n<p><strong>I brani eseguiti sono stati<\/strong>:Norma, Nabucco, Brindisi, Vissi d&#8217;arte, E lucevan le stelle, O mio babbino caro, Nessun dorma, Intermezzo sinfonico, Sinfonia n.5 in mambo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DIPIGNANO (CS) \u2013 Un\u2019atmosfera magica ha avvolto la Chiesa di San Nicola sabato 28 dicembre, in occasione del tradizionale Concerto di Natale 2024 eseguito dalla Banda Citt\u00e0 di Dipignano 1994 &#8220;F.R. Aiello&#8221;. L\u2019evento, che ha visto una partecipazione calorosa da parte della comunit\u00e0, si \u00e8 trasformato in un momento di grande condivisione e bellezza musicale. [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":247927,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-247926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=247926"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247926\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/247927"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=247926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=247926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=247926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}