{"id":247997,"date":"2025-01-05T17:00:40","date_gmt":"2025-01-05T16:00:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=247997"},"modified":"2025-01-02T13:44:24","modified_gmt":"2025-01-02T12:44:24","slug":"crisi-climatica-351-eventi-estremi-nel-2024-aumentati-di-6-volte-in-10-anni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/crisi-climatica-351-eventi-estremi-nel-2024-aumentati-di-6-volte-in-10-anni\/","title":{"rendered":"Crisi climatica: 351 eventi estremi nel 2024, aumentati di 6 volte in 10 anni"},"content":{"rendered":"<p>ROMA &#8211; Dalla siccit\u00e0 alle esondazioni causate dalle piogge intense: l&#8217;Italia \u00e8 sempre pi\u00f9 sotto scacco della crisi climatica. Nel 2024, e per il terzo anno consecutivo, sono stati oltre <strong>300 gli eventi meteo estremi che hanno colpito la Penisola<\/strong>, arrivando quota 351. Un numero in costante crescita negli ultimi dieci anni: nel 2024 gli eventi estremi sono stati quasi sei volte pi\u00f9 dei 60 del 2015, segnando un +485%. Sono i dati <strong>dell&#8217;Osservatorio Citt\u00e0 Clima di Legambiente<\/strong>, realizzato con il Gruppo Unipol, che vede l&#8217;Emilia-Romagna come la regione pi\u00f9 martoriata, seguita da Lombardia, Sicilia, Veneto e Piemonte. Il rapporto contiene poi un focus sui trasporti: 22 sono stati gli eventi meteo estremi con danni e sospensioni a treni e trasporto pubblico locale.<\/p>\n<p>Il 2024 \u00e8 stato segnato da 134 casi di allagamenti da piogge intense, 62 casi di danni da vento, 46 esondazioni fluviali che hanno causato danni, 34 eventi con danni da siccit\u00e0 prolungata, 30 danni da grandinate, 19 casi di frane causate da piogge intense, 9 danni alle infrastrutture, 8 da mareggiate, 2 al patrimonio storico e 1 caso di temperature record.<\/p>\n<h4><strong>Siccit\u00e0 prolungata e allagamenti<\/strong><\/h4>\n<p>A vedere la crescita maggiore sono stati i <strong>danni da siccit\u00e0<\/strong> prolungata (+54,5% rispetto al 2023), da esondazioni fluviali (+ 24%) e da <strong>allagamenti dovuti alle piogge intense<\/strong> (+12%), con un&#8217;Italia divisa in due tra poca e troppa acqua.<\/p>\n<p>Il <strong>Nord Italia<\/strong> risulta il pi\u00f9 colpito con <strong>198<\/strong> eventi meteo estremi, seguito dal <strong>Sud 92<\/strong> e dal <strong>Centro 61<\/strong>. A livello regionale, quest&#8217;anno l&#8217;Emilia-Romagna con 52 eventi, \u00e8 la regione pi\u00f9 martoriata dalla crisi climatica, seguita da Lombardia (49), Sicilia (43), Veneto (41) e Piemonte (22). Tra le province svetta al primo posto Bologna con 17 eventi meteo estremi, seguita da Ravenna e Roma entrambe a quota 13, Torino con 12 e Palermo con 11. Tra le grandi citt\u00e0, la Capitale \u00e8 quella pi\u00f9 colpita con 8 eventi meteo estremi, seguita da Genova (7) e Milano (6). Per quanto riguarda la siccit\u00e0, le regioni pi\u00f9 colpite sono state Sicilia (16 eventi), Sardegna (9), Basilicata (3). Sul fronte allagamenti spicca la Lombardia (con 25 eventi meteo estremi), seguita da Emilia-Romagna (22), Sicilia (15). In tema di esondazioni fluviali l&#8217;Emilia-Romagna \u00e8 al primo posto (con 14 eventi), a seguire Lombardia (8), Veneto (5).<\/p>\n<h4><strong>Eventi meteo estremi<\/strong><\/h4>\n<p>Preoccupano anche i danni che gli eventi meteo estremi stanno causando in generale sui trasporti: 22 quelli che nel 2024 hanno provocato danni e ritardi a treni e trasporto pubblico locale nella Penisola. Il rapporto ricorda anche <strong>l&#8217;ennesimo record di temperature globali registrato dal programma europeo Copernicus<\/strong> che indica il 2024 come l&#8217;anno pi\u00f9 caldo da inizio registrazioni con, per la prima volta, il superamento della soglia di <strong>1,5 \u00b0C sopra i livelli pre-industriali.<\/strong> E gli effetti, soprattutto in quota, sono sempre pi\u00f9 tangibili, con impatti sui ghiacciai, sempre pi\u00f9 sottili e in arretramento, ecosistemi e biodiversit\u00e0. Nel 2024, in Piemonte, lo zero termico in quota \u00e8 arrivato a 5.206 metri, sfiorando il record di 9 anni fa, quando era salito fino a 5.296 metri.<\/p>\n<p>&#8220;Nel 2024 l&#8217;Italia &#8211; afferma il presidente nazionale di Legambiente Stefano Ciafani &#8211; \u00e8 stata travolta da una nuova ondata di eventi meteo estremi e ancora una volta si \u00e8 fatta trovare impreparata.<strong> Il Governo Meloni,<\/strong> in oltre due anni di attivit\u00e0, <strong>non ha messo in campo nessuna strategia di prevenzione<\/strong> con interventi mirati, che permetterebbero di risparmiare il 75% delle risorse spese per riparare i danni post emergenza, e non ha stanziato i finanziamenti necessari per le azioni prioritarie del Pnacc, fondi non previsti neanche nella legge di bilancio appena approvata. \u00c8 urgente approvare anche una legge per fermare il consumo di suolo, problema affrontato in modo ideologico col DL Agricoltura vietando il fotovoltaico a terra, e il DPR per facilitare il riutilizzo delle acque reflue depurate sui terreni agricoli&#8221;.<\/p>\n<p>A preoccupare, afferma il responsabile scientifico di Legambiente Andrea Minutolo, \u00e8 il fenomeno della siccit\u00e0: &#8220;Simbolo di quest&#8217;estate il lago Pergusa, in provincia di Enna, ridotto pi\u00f9 o meno ad una pozza. L&#8217;emergenza in Sicilia \u00e8 figlia della siccit\u00e0 del Po del 2022 e di un trend collegato alla crisi climatica in continua evoluzione che rappresenta un monito severo. Per questo \u00e8 importante che il Paese definisca una strategia nazionale della gestione idrica, pi\u00f9 attenta e circolare, con interventi concreti che favoriscano l&#8217;adattamento ai cambiamenti climatici e permettano di ridurre da subito i prelievi di acqua evitandone anche gli sprechi&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Dalla siccit\u00e0 alle esondazioni causate dalle piogge intense: l&#8217;Italia \u00e8 sempre pi\u00f9 sotto scacco della crisi climatica. Nel 2024, e per il terzo anno consecutivo, sono stati oltre 300 gli eventi meteo estremi che hanno colpito la Penisola, arrivando quota 351. Un numero in costante crescita negli ultimi dieci anni: nel 2024 gli [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":235873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-247997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=247997"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/247997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/235873"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=247997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=247997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=247997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}