{"id":248223,"date":"2025-01-02T11:06:55","date_gmt":"2025-01-02T10:06:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=248223"},"modified":"2025-01-02T13:40:37","modified_gmt":"2025-01-02T12:40:37","slug":"cosenza-prendocasa-occupa-il-comune-risposte-per-lemergenza-casa-basta-promesse-e-immobilismo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-prendocasa-occupa-il-comune-risposte-per-lemergenza-casa-basta-promesse-e-immobilismo\/","title":{"rendered":"Cosenza: Prendocasa &#8216;occupa&#8217; il Comune \u00abrisposte per l&#8217;emergenza casa, basta promesse e immobilismo\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; Sulle politiche abitative &#8220;immobilismo delle istituzioni locali e regionali&#8221;. E stamattina il comitato Prendocasa ha deciso di recarsi in Comune ed occupare la sala consiliare per denunciare &#8220;l\u2019assenza di risposte concrete per affrontare l\u2019emergenza casa, un diritto fondamentale che continua a essere negato a migliaia di cosentini e cosentine&#8221;.<\/p>\n<p>&#8220;Da tempo &#8211; spiega il Comitato &#8211; chiediamo l\u2019apertura di un tavolo istituzionale che coinvolga la Prefettura, il Comune di Cosenza, la Regione Calabria e tutti gli enti preposti, per affrontare seriamente la crisi abitativa che affligge la nostra citt\u00e0. Da mesi assistiamo a <strong>interlocuzioni<\/strong> che si stanno rivelando <strong>inutili e prive di prospettiva<\/strong>. Le nostre rivendicazioni sono sistematicamente ignorate, mentre l\u2019immobilismo e l\u2019indifferenza delle istituzioni continuano a danneggiare le persone pi\u00f9 vulnerabili. Un aspetto fondamentale che vogliamo evidenziare \u00e8 la <strong>necessit\u00e0 di cessare immediatamente gli investimenti pubblici a favore dei privati nel settore immobiliare<\/strong>. \u00c8 inaccettabile che, in un momento di grave emergenza abitativa, si continuino a destinare fondi pubblici per finanziare operazioni a vantaggio dei privati, mentre i cittadini in difficolt\u00e0 restano privi di soluzioni concrete&#8221;.<\/p>\n<p>&#8220;\u00c8 necessario un cambiamento radicale nelle politiche di investimento pubblico. I fondi devono essere destinati esclusivamente a garantire il diritto alla casa, creando alloggi pubblici, ristrutturando immobili inutilizzati e finanziando interventi di edilizia residenziale pubblica&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-248224 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/prendocasa-cosenza-2-gennaio-2025-02.jpg\" alt=\"prendocasa cosenza 2 gennaio 2025 02\" width=\"481\" height=\"298\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/prendocasa-cosenza-2-gennaio-2025-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/prendocasa-cosenza-2-gennaio-2025-02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/prendocasa-cosenza-2-gennaio-2025-02-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/prendocasa-cosenza-2-gennaio-2025-02-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/prendocasa-cosenza-2-gennaio-2025-02-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/prendocasa-cosenza-2-gennaio-2025-02-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/prendocasa-cosenza-2-gennaio-2025-02-356x220.jpg 356w\" sizes=\"auto, (max-width: 481px) 100vw, 481px\" \/><\/p>\n<h4><strong>Le richieste del Comitato Prendocasa\u00a0\u00a0<\/strong><\/h4>\n<p>&#8211; Apertura immediata di un tavolo istituzionale che coinvolga la Prefettura, il Comune di Cosenza, la Regione Calabria e tutte le istituzioni competenti, per affrontare in modo strutturale l\u2019emergenza abitativa.<\/p>\n<p>&#8211; Sanare la situazione degli stabili delle ex Canossiane, di via Savoia e di Porta Piana, avviando un percorso di regolarizzazione per le famiglie che vi abitano da oltre dieci anni, garantendo loro il diritto alla residenza.<\/p>\n<p>&#8211; Regolarizzare la posizione in graduatoria per gli alloggi popolari dei cittadini che da anni vivono nelle occupazioni abitative.<\/p>\n<p>&#8211; Fermare gli investimenti pubblici a favore dei privati e destinare i fondi pubblici al diritto alla casa, con la creazione di un piano straordinario di edilizia residenziale pubblica.<\/p>\n<p>&#8211; Ristrutturazione e messa in sicurezza degli immobili pubblici inutilizzati, per destinarli a scopi abitativi.<\/p>\n<p>&#8211; Creazione di un fondo comunale temporaneo per il sostegno all\u2019affitto e l\u2019accesso alla casa per chi \u00e8 in difficolt\u00e0 economiche.<\/p>\n<p>&#8220;Non ci fermeremo &#8211; spiegano da Prendocasa &#8211; finch\u00e9 non verranno date risposte concrete ai cittadini che ogni giorno vivono l\u2019incertezza di non avere un tetto sopra la testa. L\u2019occupazione della sala consiliare \u00e8 solo l\u2019inizio: continueremo la nostra lotta finch\u00e9 il diritto alla casa non diventer\u00e0 una priorit\u00e0 politica per le istituzioni locali. \u00c8 il momento di restituire alla citt\u00e0 e ai cittadini la possibilit\u00e0 di vivere in modo dignitoso. Il 2025 non sar\u00e0 l\u2019anno delle chiacchiere e delle promesse vane&#8221;.<\/p>\n<p><strong>AGGIORNAMENTO<\/strong><\/p>\n<p>Dopo aver incontrato l\u2019assessore al welfare Buffone e i consiglieri Costanzo e Alimena gli attivisti hano lasciato il Comune con la promessa, sottoscritta in un verbale, di convocare un tavolo sull\u2019emergenza abitativa alla Prefettura entro il mese di gennaio garantendo anche il coinvolgimento della Regione Calabria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Sulle politiche abitative &#8220;immobilismo delle istituzioni locali e regionali&#8221;. E stamattina il comitato Prendocasa ha deciso di recarsi in Comune ed occupare la sala consiliare per denunciare &#8220;l\u2019assenza di risposte concrete per affrontare l\u2019emergenza casa, un diritto fondamentale che continua a essere negato a migliaia di cosentini e cosentine&#8221;. &#8220;Da tempo &#8211; spiega [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":248225,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-248223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=248223"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/248225"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=248223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=248223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=248223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}