{"id":248389,"date":"2025-01-05T08:00:31","date_gmt":"2025-01-05T07:00:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=248389"},"modified":"2025-01-04T15:03:40","modified_gmt":"2025-01-04T14:03:40","slug":"paola-proseguono-i-lavori-di-ammodernamento-ed-efficientamento-del-sistema-idrico","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/paola-proseguono-i-lavori-di-ammodernamento-ed-efficientamento-del-sistema-idrico\/","title":{"rendered":"Paola: proseguono i lavori di ammodernamento ed efficientamento del sistema idrico"},"content":{"rendered":"<p>PAOLA (CS) &#8211; Il progetto del Comune di Paola, in sinergia con la Regione Calabria, parte dal rinnovamento delle infrastrutture, \u00e8 stato avviato un piano di ammodernamento di quelle idriche, <strong>sostituendo vecchie tubature dei tanti serbatoi<\/strong> e migliorando la rete di distribuzione. &#8220;\u00c8 stato poi installato un <strong>sistema di monitoraggio continuo<\/strong> per individuare e risolvere rapidamente eventuali problemi&#8221; annuncia l&#8217;assessore comunale <strong>Massimo Focetola<\/strong>. &#8220;Squadre di tecnici sono costantemente impegnate nella manutenzione preventiva e correttiva delle infrastrutture. Grazie ai sensori installati su tutti i serbatoi, \u00e8 possibile monitorare costantemente la portata, la <strong>pressione dell&#8217;acqua e il livello delle vasche<\/strong>. Questo sistema di monitoraggio avanzato consente di individuare rapidamente eventuali perdite o anomalie, permettendo interventi tempestivi mirati&#8221;.<\/p>\n<p>C&#8217;\u00e8, ancora, &#8220;il <strong>progetto di digitalizzazione<\/strong>, che include <strong>l&#8217;uso di tecnologie avanzate per creare mappe GEO cartografiche<\/strong> precise di tutta la rete idrica che comprende la linea delle <strong>condutture, i pozzetti, le sorgenti, i serbatoi e i contatori<\/strong>. Al termine dei lavori tutto sar\u00e0 rilevato e georeferenziato, permettendo una visione dettagliata e in tempo reale dello stato delle infrastrutture. La digitalizzazione della rete idrica ha portato ad una significativa riduzione delle perdite d&#8217;acqua e ad un miglioramento dell&#8217;efficienza operativa. A tutto questo, si aggiunge il lavoro certosino svolto con abnegazione e seriet\u00e0&#8221;.<\/p>\n<p>Sempre l&#8217;assessore Focetola sottolinea: &#8220;In questi mesi, \u00e8 stata rilevata e risolta una grave perdita, che quanto riferito dagli operatori del settore, era presente da oltre 30 anni e fuoriusciva dal muro di contenimento a ridosso della <strong>strada di Sant&#8217;Agata sotto il Faro<\/strong>. Una fuoriuscita d&#8217;acqua che tanti definivano sorgente, pozzo, ecc. In quest&#8217;ultimo periodo, con diverse richieste a mia firma, sono state sollecitate una serie di ricerche e rilievi per accertare se effettivamente non fosse acqua che provenisse dal serbatoio. Alla conclusione delle tante indagini \u00e8 emerso che l&#8217;acqua provenisse dal serbatoio <strong>zona Viale dei Giardini<\/strong> che eroga su buona parte di Sant&#8217;Agata e non solo.<\/p>\n<p>La <strong>perdita<\/strong>, cos\u00ec come evidenziato dai dati, <strong>era di 7\/8 litri al secondo<\/strong>. Un equivalente di 691mila litri al giorno di acqua che si \u00e8 persa nel sottosuolo e che solo oggi torna a essere disponibile per soddisfare le esigenze dei cittadini! Le riflessioni economiche sono dovute&#8221;. Ed ancora: &#8220;Un ulteriore intervento \u00e8 stato effettuato anche presso <strong>contrada Tina<\/strong>, dove \u00e8 stato sostituito completamente il tubo che alimentava tutte le strutture sportive, anche l\u00ec, con gravi perdite. Altra sollecitazione \u00e8 stata fatta in merito alla sostituzione dei contatori presso le strutture pubbliche e l&#8217;installazione ove mancasse. Anche qui per monitorare il consumo e accertare ulteriori criticit\u00e0&#8221;.\u00a0&#8220;Non si vuole pi\u00f9 perdere tempo a rispondere a polemiche e strumentalizzazioni in merito al <strong>Sistema Idrico di Paola<\/strong>, ma si vogliono impiegare tutte le risorse a nostra disposizione sul problema facendo parlare semplicemente i risultati&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PAOLA (CS) &#8211; Il progetto del Comune di Paola, in sinergia con la Regione Calabria, parte dal rinnovamento delle infrastrutture, \u00e8 stato avviato un piano di ammodernamento di quelle idriche, sostituendo vecchie tubature dei tanti serbatoi e migliorando la rete di distribuzione. &#8220;\u00c8 stato poi installato un sistema di monitoraggio continuo per individuare e risolvere [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":248390,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-248389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=248389"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248389\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/248390"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=248389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=248389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=248389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}