{"id":248397,"date":"2025-01-04T17:30:27","date_gmt":"2025-01-04T16:30:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=248397"},"modified":"2025-01-04T17:06:11","modified_gmt":"2025-01-04T16:06:11","slug":"capodanno-rai-antoniozzi-il-prossimo-anno-si-faccia-a-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/capodanno-rai-antoniozzi-il-prossimo-anno-si-faccia-a-cosenza\/","title":{"rendered":"Capodanno Rai, Antoniozzi \u00abil prossimo anno si faccia a Cosenza\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;Se avremo anche il prossimo Capodanno su Raiuno, sar\u00e0 un&#8217;altra importante occasione di visibilit\u00e0 per tutta la Calabria. Lo afferma il vicecapogruppo di FdI alla Camera, Alfredo Antoniozzi. &#8220;Il primo &#8211; aggiunge &#8211; si \u00e8 tenuto a Crotone, nell&#8217;area della Magna Graecia. Il secondo a Reggio Calabria, unica Citt\u00e0 metropolitana della regione. Se ce ne sar\u00e0 un altro, mi piacerebbe che si svolgesse a Cosenza, che \u00e8 la provincia pi\u00f9 grande ed \u00e8 la mia citt\u00e0. Tuttavia odio i campanilismi e se la Regione riterr\u00e0 opportuno farlo in altre aree o citt\u00e0 sar\u00e0 comunque un successo per tutta la Calabria&#8221;.<\/p>\n<p>&#8220;C&#8217;\u00e8 Catanzaro, c&#8217;\u00e8 Tropea, c&#8217;\u00e8 l&#8217;area di Sibari, il vibonese. Tutte zone attraenti e seppure sia legittimo che ognuno faccia il tifo per la propria citt\u00e0. L&#8217;importante \u00e8 capire che siamo tutti calabresi e che questa scelta non diventi motivo di derby calcistici. <strong>Cosenza \u00e8 stata brava a ingaggiare un cantante che l&#8217;ha portata sui canali Sky la notte di Capodanno<\/strong>, mentre altre citt\u00e0 forse potevano scegliere meglio.<\/p>\n<p>&#8220;Spendere soldi vincolati per il turismo in attivit\u00e0 che danno questa visibilit\u00e0 &#8211; dice ancora Antoniozzi- \u00e8 un investimento giusto. Coltivo ancora il sogno che Cosenza possa ambire nel futuro ad essere Capitale della cultura e ne parler\u00f2 con il sindaco Caruso. Credo che la citt\u00e0 meriti considerazione a livello nazionale e penso che nel futuro si possa lavorare insieme, a prescindere dai colori politici, perch\u00e9 il centro storico e la ricchezza culturale di Cosenza vengano valorizzate&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;Se avremo anche il prossimo Capodanno su Raiuno, sar\u00e0 un&#8217;altra importante occasione di visibilit\u00e0 per tutta la Calabria. Lo afferma il vicecapogruppo di FdI alla Camera, Alfredo Antoniozzi. &#8220;Il primo &#8211; aggiunge &#8211; si \u00e8 tenuto a Crotone, nell&#8217;area della Magna Graecia. Il secondo a Reggio Calabria, unica Citt\u00e0 metropolitana della regione. Se [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":248117,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[19],"class_list":["post-248397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senza-categoria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=248397"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/248117"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=248397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=248397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=248397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}