{"id":248421,"date":"2025-01-05T10:58:08","date_gmt":"2025-01-05T09:58:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=248421"},"modified":"2025-01-05T14:00:29","modified_gmt":"2025-01-05T13:00:29","slug":"si-e-spento-70-anni-pino-chianello-ex-amministratore-delegato-del-cosenza-calcio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/si-e-spento-70-anni-pino-chianello-ex-amministratore-delegato-del-cosenza-calcio\/","title":{"rendered":"Si \u00e8 spento a 70 anni Pino Chianello, ex amministratore delegato del Cosenza Calcio"},"content":{"rendered":"<p>PAOLA (CS) &#8211; Originario di Paola, <strong>Pino Chianello<\/strong>, \u00e8 <strong>deceduto all&#8217;et\u00e0 di 70 anni<\/strong>, dopo una lunga malattia. Figura rappresentativa del calcio calabrese, si \u00e8 spento questa mattina. La citt\u00e0 dei Bruzi lo ricorda per il suo ruolo da <strong>amministratore delegato del Cosenza calcio,<\/strong> e per il contributo relativo al trasferimento del titolo sportivo del Rende a Cosenza; operazione che diede vita al ritorno tra i professionisti del club rossobl\u00f9, ma anche per le promozioni dalla serie D alla Seconda divisione e dalla Seconda divisione alla Prima divisione negli anni del Dg Massimiliano Mirabelli e di Mimmo Toscano, allenatore del Cosenza.<\/p>\n<p>Anche la <strong>Societ\u00e0 Cosenza Calcio<\/strong>, in tutte le sue componenti, ha espresso profondo cordoglio per la scomparsa dell\u2019imprenditore Pino Chianello. &#8220;Ex dirigente del Cosenza Calcio, <strong>persona saggia e cordiale<\/strong>, da sempre vicina ai colori rossobl\u00f9. Alla famiglia giungano le pi\u00f9 sentite condoglianze&#8221;.<\/p>\n<h4>Franz Caruso \u00abgrande sensazione di vuoto\u00bb<\/h4>\n<p>\u201cApprendo con <strong>profonda tristezza<\/strong> della scomparsa del caro amico Pino Chianello, imprenditore di Paola e, in passato, amministratore delegato del Cosenza Calcio. A lui e alla sua famiglia mi legava un rapporto di profonda amicizia, soprattutto con il fratello Walter, scomparso qualche anno fa, che era un punto di riferimento importante presso il Tribunale di Paola. Fu proprio in quella circostanza che i rapporti con Pino Chianello e con tutti i familiari si rafforzarono ancora di pi\u00f9\u201d. Sono le parole del sindaco Franz Caruso, che ha espresso profondo cordoglio per la scomparsa dell\u2019imprenditore paolano.<\/p>\n<p>\u201cGrande appassionato di sport, e di calcio in modo particolare, Pino Chianello \u2013 ha sottolineato nel suo messaggio di cordoglio il Sindaco Franz Caruso &#8211; fu anche dirigente del Cosenza calcio e Presidente del Centro sportivo \u201cChianello\u201d di Paola, nella cui veste si occup\u00f2, con grande dedizione, della formazione di giovani calciatori, collaborando con la Paolana ed aprendo la sua scuola calcio a tutti i settori giovanili dei paesi limitrofi. Fu, inoltre, un imprenditore molto apprezzato ed operoso anche nel sociale. Il fatto che non sia pi\u00f9 tra noi mi fa percepire una grande sensazione di vuoto che \u00e8 quella che si impadronisce di ognuno quando scompare un caro amico e, nel caso specifico, quando ci sono legami cos\u00ec saldi con la sua famiglia. In questo triste momento \u2013 ha concluso il primo cittadino di Cosenza &#8211; giungano a tutti i familiari di Pino Chianello i sentimenti della mia pi\u00f9 affettuosa vicinanza e le pi\u00f9 sentite condoglianze di tutta l\u2019Amministrazione comunale\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-248430 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Pino-Chianello-1.jpg\" alt=\"\" width=\"234\" height=\"322\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Pino-Chianello-1.jpg 457w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Pino-Chianello-1-218x300.jpg 218w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Pino-Chianello-1-305x420.jpg 305w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Pino-Chianello-1-150x206.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Pino-Chianello-1-300x413.jpg 300w\" sizes=\"auto, (max-width: 234px) 100vw, 234px\" \/><\/p>\n<h4>Il cordoglio del sindaco di Paola \u00abse ne va un pezzo del nostro cuore\u00bb<\/h4>\n<p>&#8220;Con Pino Chianello se ne va un pezzo del nostro cuore e della storia imprenditoriale, sportiva e sociale della nostra Citt\u00e0&#8221;. Sono le parole di cordoglio del primo cittadino di Paola, Giovanni Politano. &#8220;Una scomparsa che ci addolora e che lascia un vuoto incolmabile in noi tutti. E, credetemi: non sono parole di circostanza. Non potranno mai esserlo, soprattutto per ci\u00f2 che ha rappresentato Pino e per ci\u00f2 che ha fatto, per la nostra Comunit\u00e0, nello sport, nell&#8217;ambito sociale e sotto l&#8217;aspetto imprenditoriale&#8221;.<\/p>\n<p>&#8220;Un impegno costante, serio, concreto, umano, che lo ha visto sempre in prima linea, sempre pronto ad affrontare nuove sfide e sempre a sostegno dei pi\u00f9 deboli. Un esempio di caparbiet\u00e0 e di valori, che ci accompagner\u00e0 nel tempo. A Lui va il nostro dolce ricordo. Alla Sua Famiglia ed ai suoi collaboratori, l&#8217;abbraccio di tutti i Paolani&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PAOLA (CS) &#8211; Originario di Paola, Pino Chianello, \u00e8 deceduto all&#8217;et\u00e0 di 70 anni, dopo una lunga malattia. Figura rappresentativa del calcio calabrese, si \u00e8 spento questa mattina. La citt\u00e0 dei Bruzi lo ricorda per il suo ruolo da amministratore delegato del Cosenza calcio, e per il contributo relativo al trasferimento del titolo sportivo del [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":248422,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[19],"class_list":["post-248421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=248421"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248421\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/248422"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=248421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=248421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=248421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}