{"id":248590,"date":"2025-01-08T08:23:04","date_gmt":"2025-01-08T07:23:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=248590"},"modified":"2025-01-08T08:23:04","modified_gmt":"2025-01-08T07:23:04","slug":"morte-serafino-congi-la-comunita-di-san-giovanni-in-fiore-rivendica-il-diritto-alla-salute","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/morte-serafino-congi-la-comunita-di-san-giovanni-in-fiore-rivendica-il-diritto-alla-salute\/","title":{"rendered":"Morte Serafino Congi, la comunit\u00e0 di San Giovanni in Fiore rivendica il diritto alla salute"},"content":{"rendered":"<p>SAN GIOVANNI IN FIORE &#8211; Una passeggiata silenziosa ha attraversato le vie della cittadina di <strong>San Giovanni in Fiore<\/strong>. <strong>Un corteo di protesta, composto ma deciso, formato da oltre 2000 persone.<\/strong> Istituzioni, associazioni e cittadini tutti insieme per esprimere la propria indignazione dopo la morte di <strong>Serafino Congi<\/strong> a soli 48 anni, avvenuta lo scorso 4 gennaio, perch\u00e9 a seguito di un malore era stato trasportato al Pronto Soccorso di San Giovanni in Fiore e solo dopo oltre due ore \u00e8 giunta un\u2019ambulanza per trasportarlo all\u2019Ospedale Civile dell\u2019Annunziata di Cosenza. Un\u2019ambulanza per\u00f2 sprovvista di un medico. <strong>L\u2019uomo, sposato con due figlie \u00e8 morto durante il tragitto per arresto cardiaco<\/strong>. Il corteo si \u00e8 fermato poi sotto l\u2019abitazione di <strong>Serafino Congi<\/strong>, per salutare con un caloroso applauso i familiari e la moglie, per proseguire poi fino all\u2019ospedale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN GIOVANNI IN FIORE &#8211; Una passeggiata silenziosa ha attraversato le vie della cittadina di San Giovanni in Fiore. Un corteo di protesta, composto ma deciso, formato da oltre 2000 persone. Istituzioni, associazioni e cittadini tutti insieme per esprimere la propria indignazione dopo la morte di Serafino Congi a soli 48 anni, avvenuta lo scorso [&hellip;]<\/p>\n","protected":false},"author":66,"featured_media":248591,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19,135],"class_list":["post-248590","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-provincia","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=248590"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/248591"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=248590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=248590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=248590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}