{"id":248598,"date":"2025-01-08T09:43:40","date_gmt":"2025-01-08T08:43:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=248598"},"modified":"2025-01-08T09:55:25","modified_gmt":"2025-01-08T08:55:25","slug":"entrano-in-chiesa-fingendosi-bisognosi-sequestrano-il-parroco-e-lo-minacciano-per-derubarlo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/entrano-in-chiesa-fingendosi-bisognosi-sequestrano-il-parroco-e-lo-minacciano-per-derubarlo\/","title":{"rendered":"Entrano in chiesa fingendosi bisognosi. Sequestrano il parroco e lo minacciano per derubarlo"},"content":{"rendered":"<p>ARCHI (RC) &#8211; <strong>La chiesa di\u00a0Maria Santissima del Carmelo ad Archi violata da due individui che hanno addirittura sequestrato il parroco, Don Danilo Latella, fingendosi bisognosi.<\/strong> I due individui, con la scusa di un chiedere aiuto (generi alimentari) sono entrati nell&#8217;ufficio parrocchiale, incappucciandosi e tirando fuori un oggetto atto ad offendere utilizzato come arma.\u00a0<strong>Hanno tenuto in ostaggio il parroco<\/strong> affinch\u00e9 consegnasse loro una somma di denaro. L&#8217;intera vicenda si \u00e8 svolta in pochi minuti, lunghissimi per il parroco che <strong>ha avuto comunque la lucidit\u00e0 necessaria per scappare e chiedere aiuto,<\/strong> mentre i due fuggivano prima dell&#8217;arrivo delle Forze dell&#8217;Ordine.<\/p>\n<p>L\u2019episodio, gi\u00e0 denunciato alle autorit\u00e0 competenti, ha scosso profondamente la comunit\u00e0 parrocchiale &#8220;<strong>Don Danilo sta bene spavento e non ha subito alcun danno fisico a parte un grande spavento<\/strong>. Abbiamo deciso di scrivere questo comunicato per garantire trasparenza e per evitare la diffusione di notizie false o distorte che potrebbero creare ulteriore disagio e preoccupazione nella Comunit\u00e0&#8221;.<\/p>\n<p><strong>&#8220;L&#8217;accaduto \u00e8 stato prontamente denunciato alle autorit\u00e0 competenti, che sono gi\u00e0 al lavoro per individuare i responsabili<\/strong>. Questo evento, doloroso e inaccettabile, rappresenta un duro colpo non solo per Don Danilo, ma per tutta la nostra comunit\u00e0 di Archi. <strong>Un gesto cosi vile, che colpisce un luogo di fede e una persona che si dedica con amore e sacrificio, non pu\u00f2 essere tollerato<\/strong>. Invitiamo tutti i fedeli a unirsi nella preghiera per Don Danilo e per intera Comunit\u00e0 parrocchiale che, forte e unita, continuer\u00e0 il suo cammino nella fede senza lasciarsi intimidire dal Male. Ringraziamo tutti per vostro sostegno e la vicinanza in questo momento. <strong>Continuiamo camminare insieme, guidati dall&#8217;amore, dalla speranza e dalla forza della nostra fede<\/strong>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ARCHI (RC) &#8211; La chiesa di\u00a0Maria Santissima del Carmelo ad Archi violata da due individui che hanno addirittura sequestrato il parroco, Don Danilo Latella, fingendosi bisognosi. I due individui, con la scusa di un chiedere aiuto (generi alimentari) sono entrati nell&#8217;ufficio parrocchiale, incappucciandosi e tirando fuori un oggetto atto ad offendere utilizzato come arma.\u00a0Hanno tenuto [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":248599,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-248598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=248598"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/248599"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=248598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=248598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=248598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}