{"id":248679,"date":"2025-01-09T08:16:48","date_gmt":"2025-01-09T07:16:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=248679"},"modified":"2025-01-09T08:20:49","modified_gmt":"2025-01-09T07:20:49","slug":"convalidato-il-fermo-per-un-piromane-seriale-60enne-accusato-di-aver-incendiato-11-autovetture","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/convalidato-il-fermo-per-un-piromane-seriale-60enne-accusato-di-aver-incendiato-11-autovetture\/","title":{"rendered":"Convalidato il fermo per un piromane seriale, 60enne accusato di aver incendiato 11 autovetture"},"content":{"rendered":"<p>MARINA DI GIOIOSA IONICA (RC) &#8211; Una lunga ed inquietante spirale di incendi dolosi che ha terrorizzato la comunit\u00e0 di Marina di Gioiosa Ionica sembra aver trovato il proprio epilogo. I carabinieri hanno arrestato <strong>uomo di 60 anni<\/strong>, residente nella zona ed il suo fermo convalidato dalla Procura di Locri. Il suo nome, legato a una <strong>serie di atti di vandalismo<\/strong>, \u00e8 ora al centro di un\u2019inchiesta che ha messo in luce un inquietante<strong> piano criminale<\/strong>. La storia di questo seriale autore di incendi inizia, infatti, <strong>nella notte del 14 ottobre 2024<\/strong>, quando la comunit\u00e0 di Marina di Gioiosa Ionica comincia a tremare di fronte a una repentina serie di attentati incendiari, che nel corso dei mesi successivi non sembrava avere fine.<\/p>\n<p><strong>Undici episodi<\/strong>, ognuno dei quali pi\u00f9 distruttivo e pericoloso del precedente, commessi in danno di <strong>altrettante autovetture<\/strong>, che hanno profondamente scosso le vittime e messo in pericolo gli abitanti delle tante abitazioni lambite dalle fiamme che divampavano irrefrenabilmente sulle auto lasciate in sosta.<\/p>\n<p>Le indagini, condotte con incessante scrupolo, hanno in breve evidenziato la pericolosit\u00e0 dell\u2019autore, che ha ben dimostrato di conoscere con accuratezza il territorio della cittadina e che, con una freddezza sprezzante delle potenziali conseguenze, ha continuato a pianificare con dovizia di particolari ogni singolo colpo. <strong>L\u2019uomo, infatti, non solo agiva di notte,<\/strong> approfittando della naturale copertura fornitagli dall\u2019oscurit\u00e0, ma teneva in debita considerazione l\u2019impegno che ogni evento avrebbe determinato per le forze di soccorso e per le pattuglie dell\u2019Arma. <strong>Di qui la sua pericolosa audacia<\/strong>: sfruttando i concitati sforzi rivolti allo spegnimento di un incendio appena appiccato, colpiva nuovamente, poco dopo, in un distante punto della cittadina, certo di realizzare eventi sempre pi\u00f9 difficili da gestire tempestivamente.<\/p>\n<h4><strong>Spinto da dissapori personali<\/strong><\/h4>\n<p>Le indagini, lunghe e complesse, coordinate dalla Procura della Repubblica di Locri, hanno rivelato una trama di <strong>vendetta e risentimento<\/strong>: l\u2019uomo avrebbe infatti agito spinto da dissapori personali con alcune delle sue vittime, spesso professionisti noti della zona. Le sue motivazioni non erano solo legate al furioso desiderio di distruggere, ma a un rancore profondo che lo spingeva a colpire nel cuore della sua comunit\u00e0, consapevole del clima di terrore che avrebbe continuato ad alimentare.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-248681 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/incendi-marina-gioiosa.jpg\" alt=\"\" width=\"538\" height=\"333\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/incendi-marina-gioiosa.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/incendi-marina-gioiosa-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/incendi-marina-gioiosa-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/incendi-marina-gioiosa-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/incendi-marina-gioiosa-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/incendi-marina-gioiosa-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/incendi-marina-gioiosa-356x220.jpg 356w\" sizes=\"auto, (max-width: 538px) 100vw, 538px\" \/><\/p>\n<p>I Carabinieri hanno dovuto mettere insieme un puzzle articolato e complesso: raccogliere ogni frammento di prova, ogni testimonianza, ogni indizio. <strong>Il rinvenimento di un ordigno incendiario, non innescatosi correttamente, ha consentito di acquisire fondamentali elementi per lo sviluppo delle indagini:<\/strong> un ordigno rudimentale (ma, per ci\u00f2 solo, non meno pericoloso) i cui materiali costituitivi, di comune uso, sono stati trovati nella materiale disponibilit\u00e0 dell\u2019indagato, sulle cui tracce si erano ormai messi i Carabinieri. Anche per questo, forse, l\u2019uomo &#8211; dopo i successivi eventi incendiari &#8211; ha cominciato a rendersi irreperibile, cos\u00ec da ostacolare l\u2019attivit\u00e0 degli inquirenti.<\/p>\n<p>Le maniacali accortezze non sono state per\u00f2 sufficienti ad impedire la puntigliosa ricostruzione degli eventi e la raccolta degli indizi a carico dell\u2019uomo che oggi, grazie al puntiglioso lavoro dei Carabinieri di Marina di Gioiosa Ionica ed al fondamentale coordinamento della Procura, dovr\u00e0 rispondere al Tribunale di Locri della lunga scia di inquietudini e paure instillata nella cittadinanza, finalmente restituita alla propria serenit\u00e0.<br \/>\nIl Procedimento si trova nella fase delle indagini preliminari e per l\u2019indagato vale il principio di non colpevolezza fino a condanna definitiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MARINA DI GIOIOSA IONICA (RC) &#8211; Una lunga ed inquietante spirale di incendi dolosi che ha terrorizzato la comunit\u00e0 di Marina di Gioiosa Ionica sembra aver trovato il proprio epilogo. I carabinieri hanno arrestato uomo di 60 anni, residente nella zona ed il suo fermo convalidato dalla Procura di Locri. Il suo nome, legato a [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":248680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19,135],"class_list":["post-248679","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-calabria","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=248679"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/248680"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=248679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=248679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=248679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}