{"id":248684,"date":"2025-01-09T09:44:48","date_gmt":"2025-01-09T08:44:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=248684"},"modified":"2025-01-09T09:48:18","modified_gmt":"2025-01-09T08:48:18","slug":"un-piano-che-sembrava-perfetto-per-rapinare-un-ufficio-postale-i-carabinieri-arrestano-3-persone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/un-piano-che-sembrava-perfetto-per-rapinare-un-ufficio-postale-i-carabinieri-arrestano-3-persone\/","title":{"rendered":"Un piano che sembrava perfetto per rapinare un ufficio postale. I carabinieri arrestano 3 persone"},"content":{"rendered":"<p>SAN COSTANTINO CALABRO (VV) &#8211; <strong>Un colpo studiato nei dettagli<\/strong>, u<strong>n\u2019indagine complessa e un lavoro incessante<\/strong>: \u00e8 cos\u00ec che <strong>i Carabinieri della Stazione di San Costantino Calabro sono riusciti a dare un volto e un nome ai responsabili della rapina avvenuta il 30 ottobre scorso ai danni dell\u2019ufficio postale del paese<\/strong>. Ancora una volta, la Stazione Carabinieri, ha confermato la propria valenza strategica quale presidio di sicurezza, operando con metodicit\u00e0 e avvalendosi della profonda conoscenza del territorio oltre che della costante presenza operativa sul campo. La vicenda aveva scosso il piccolo centro di San Costantino.<\/p>\n<p><strong>Due uomini, ritenuti vicini a un gruppo criminale attivo fuori provincia, avevano messo a segno il colpo utilizzando un piano che, almeno all\u2019apparenza, sembrava perfetto<\/strong>. Per non destare sospetti, i rapinatori si erano mossi con due auto: una \u201cpulita\u201d e una rubata. <strong>L\u2019auto pulita era stata nascosta alla periferia del paese<\/strong>, permettendo loro di proseguire verso l\u2019ufficio postale con il mezzo rubato. Terminato il colpo, i due erano tornati all\u2019auto nascosta, con l\u2019intenzione di lasciare la zona e far perdere le proprie tracce.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/7ML7gWVew88?si=ETdoNfYAU8kPNLx6\" width=\"640\" height=\"480\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Le indagini, avviate tempestivamente, hanno tratto linfa vitale dall\u2019analisi delle i<strong>mmagini della telecamera di sorveglianza installata presso il postamat<\/strong>. Nonostante l\u2019accurato travisamento adottato dai rapinatori \u2013 i quali <strong>indossavano barbe finte, occhiali da sole e copricapi \u2013 i militari sono riusciti a risalire alla loro identit\u00e0,<\/strong> ricostruendo con precisione i movimenti e il modus operandi grazie all\u2019integrazione di molteplici fonti di prova, tra cui riprese video, rilievi tecnici sul luogo e incroci di dati investigativi.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Carabinieri-vibo-rapina.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-248687 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Carabinieri-vibo-rapina.jpg\" alt=\"Carabinieri vibo rapina\" width=\"574\" height=\"397\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Carabinieri-vibo-rapina.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Carabinieri-vibo-rapina-300x207.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Carabinieri-vibo-rapina-768x530.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Carabinieri-vibo-rapina-608x420.jpg 608w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Carabinieri-vibo-rapina-150x104.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Carabinieri-vibo-rapina-218x150.jpg 218w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Carabinieri-vibo-rapina-696x481.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/Carabinieri-vibo-rapina-100x70.jpg 100w\" sizes=\"auto, (max-width: 574px) 100vw, 574px\" \/><\/a><\/p>\n<p>La svolta \u00e8 arrivata con le operazioni di cattura portate a termine dalle Stazioni Carabinieri di San Costantino Francica e Mileto, coadiuvate dal personale della Tenenza di Rosarno. Uno dei rapinatori, forse resosi conto dell\u2019inevitabilit\u00e0 della situazione, ha tentato l\u2019ultima carta: la fuga. S<strong>i \u00e8 lanciato tra le campagne, cercando di approfittare della vegetazione per dileguarsi, ma i Carabinieri con il loro dispositivo di cinturazione, hanno bloccato il suo tentativo<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN COSTANTINO CALABRO (VV) &#8211; Un colpo studiato nei dettagli, un\u2019indagine complessa e un lavoro incessante: \u00e8 cos\u00ec che i Carabinieri della Stazione di San Costantino Calabro sono riusciti a dare un volto e un nome ai responsabili della rapina avvenuta il 30 ottobre scorso ai danni dell\u2019ufficio postale del paese. Ancora una volta, la [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":248685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19,135],"class_list":["post-248684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina","tag-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=248684"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248684\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/248685"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=248684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=248684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=248684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}