{"id":248876,"date":"2025-01-10T15:12:44","date_gmt":"2025-01-10T14:12:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=248876"},"modified":"2025-01-10T17:36:47","modified_gmt":"2025-01-10T16:36:47","slug":"rapinano-un-supermercato-a-castrovillari-mascherati-e-armati-di-coltello-3-arresti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/rapinano-un-supermercato-a-castrovillari-mascherati-e-armati-di-coltello-3-arresti\/","title":{"rendered":"Rapinano un supermercato a Castrovillari mascherati e armati di coltello: 3 arresti"},"content":{"rendered":"<p>CASTROVILLARI (CS) &#8211;<strong> Tre giovani, tra i 23 e 27 anni,<\/strong> due dei quali gi\u00e0 noti alle forze dell&#8217;ordine, <strong>sono stati arrestati e posti ai domiciliari<\/strong> dagli agenti del Commissariato di Ps di Castrovillari e dai carabinieri della locale Compagnia con l&#8217;accusa di rapina. Il terzetto \u00e8 ritenuto responsabile della rapina a mano armata effettuata lo scorso 27 settembre ai danni di un supermercato di Castrovillari. <strong>Il colpo venne compiuto la sera del 27 settembre scorso da due malviventi travisati e armati di coltello<\/strong> che, dopo avere minacciato, la cassiera riuscirono ad impossessarsi dell&#8217;intero incasso della giornata. Agguantato il bottino i due si allontanarono facendo perdere le loro tracce.<\/p>\n<p>Le attivit\u00e0 indagini subito avviate dai carabinieri, con l&#8217;ausilio della Polizia di Stato hanno permesso, pochi giorni dopo, di ricostruire la dinamica del fatto e di identificare i presunti autori. Dall&#8217;analisi delle immagini di videosorveglianza comunali e di altri esercizi commerciali, infatti, si \u00e8 potuto visionare l&#8217;arrivo dei tre, il loro percorso tra le vie cittadine e il sopralluogo nell&#8217;area individuata. I tre si sono poi cambiati d&#8217;abito e, in due, sono tornati nei pressi dell&#8217;esercizio commerciale per compiere la rapina. Una volta portato a termine il piano <strong>la coppia di malviventi si \u00e8 allontanata abbandonando, lungo la strada, gli abiti e il coltello<\/strong> trovati l&#8217;indomani dai poliziotti, per ricongiungersi al terzo complice e sparire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Tre giovani, tra i 23 e 27 anni, due dei quali gi\u00e0 noti alle forze dell&#8217;ordine, sono stati arrestati e posti ai domiciliari dagli agenti del Commissariato di Ps di Castrovillari e dai carabinieri della locale Compagnia con l&#8217;accusa di rapina. Il terzetto \u00e8 ritenuto responsabile della rapina a mano armata effettuata [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":248847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-248876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=248876"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/248847"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=248876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=248876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=248876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}