{"id":248987,"date":"2025-01-12T11:47:24","date_gmt":"2025-01-12T10:47:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=248987"},"modified":"2025-01-12T11:47:24","modified_gmt":"2025-01-12T10:47:24","slug":"la-statua-di-mancini-non-si-sposta-la-storia-non-si-sfratta-sabato-prossimo-flash-mob","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/la-statua-di-mancini-non-si-sposta-la-storia-non-si-sfratta-sabato-prossimo-flash-mob\/","title":{"rendered":"\u201cLa statua di Mancini non si sposta, la storia non si sfratta\u201d. Sabato prossimo Flash mob"},"content":{"rendered":"<p>COSENZA \u2013 Continua a tenere banco a Cosenza la questione relativa allo <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/cosenza\/fondazione-mancini-il-sindaco-di-cosenza-vuole-sfrattare-la-statua-davanti-il-comune\" target=\"_blank\" rel=\"noopener\">spostamento della statua<\/a> in onore dell\u2019ex sindaco e leader socialista<strong> Giacomo Mancini<\/strong> che il Comune di Cosenza vuole spostare dalla sua sede originale e nella quale era stata collocata il 25 aprile del 22 (nell\u2019ultimo tratto pedonale di Corso Mazzini). Il sindaco<a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/statua-mancini-caruso-replica-non-e-uno-sfratto-verra-spostata-nella-piazza-a-lui-intitolata\" target=\"_blank\" rel=\"noopener\"> aveva replicato<\/a> spiegando che la statua si trova in piazza Carratelli e che lo spostamento arrivava \u201c<strong>rispondendo a delle richieste che provengono dai cittadini che abitano nella piazza, valutando la necessit\u00e0 di spostarla nel luogo che appunto porta il suo nome, piazza Giacomo Mancini\u201d<\/strong>.<\/p>\n<h3>Statua di Mancini: sabato prossimo flash mob<\/h3>\n<p>Scelta che <strong>ha trovato la disapprovazione immediata della Fondazione Giacomo Mancini<\/strong> che per sabato prossimo 18 gennaio, proprio con i 10 giorni di tempo dati alla Fondazione stessa per scegliere una nuova collocazione, <strong>alle ore 11.30, accogliendo le sollecitazioni impetuose che provengono da tanti cittadini indignati, ha dato a tutti appuntamento per un flashmob<\/strong> e un presidio intorno alla statua per ribadire una volta di pi\u00f9 che<strong><em> \u00abNo! il Leone non si sposta\u00bb.<\/em><\/strong><\/p>\n<p>\u00ab<strong>Alla pec del sindaco replicheremo tutti insieme con una risposta di popolo, di donne e uomini che si sono sentiti offesi per il trattamento riservato alla memoria di Giacomo Mancini,<\/strong> <em>alla statua che lo raffigura e alla storia della nostra comunit\u00e0. Una risposta di cittadine e cittadini che &#8211;<\/em> conclude la nota della FGM<em> &#8211; insieme e in modo corale dicono che la statua non si sposta e che la storia non si sfratta<\/em>.\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA \u2013 Continua a tenere banco a Cosenza la questione relativa allo spostamento della statua in onore dell\u2019ex sindaco e leader socialista Giacomo Mancini che il Comune di Cosenza vuole spostare dalla sua sede originale e nella quale era stata collocata il 25 aprile del 22 (nell\u2019ultimo tratto pedonale di Corso Mazzini). Il sindaco aveva [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":248988,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-248987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=248987"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/248988"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=248987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=248987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=248987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}