{"id":249045,"date":"2025-01-13T16:00:29","date_gmt":"2025-01-13T15:00:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=249045"},"modified":"2025-01-13T12:50:45","modified_gmt":"2025-01-13T11:50:45","slug":"migranti-e-accoglienza-lassociazione-matrangolo-sulle-pagine-di-le-monde","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/migranti-e-accoglienza-lassociazione-matrangolo-sulle-pagine-di-le-monde\/","title":{"rendered":"Migranti e accoglienza, l&#8217;associazione &#8220;Matrangolo&#8221; sulle pagine di &#8220;Le Monde&#8221;"},"content":{"rendered":"<p>ACQUAFORMOSA (CS) &#8211; Sul sito del quotidiano francese <a href=\"https:\/\/www.lemonde.fr\/m-le-mag\/article\/2025\/01\/11\/en-calabre-la-migration-dans-les-veines-giovanni-manoccio_6492175_4500055.html\" rel=\"noopener\">\u201cLe Monde\u201d<\/a>, sabato 11 gennaio, \u00e8 apparso un articolo dedicato all&#8217;azione svolta ormai da anni dall&#8217;Associazione \u201cDon Vincenzo Matrangolo\u201d in tema di migranti. <strong>\u201cIn Calabria, la migrazione nelle vene di Giovanni Manoccio\u201d<\/strong> \u00e8 il <strong>titolo<\/strong> che il giornale ha voluto dare all&#8217;articolo proprio per enfatizzare l&#8217;impegno e il lavoro che <strong>Manoccio continua a profondere in favore di chi chiede asilo. <\/strong>Il pezzo, firmato da Camille Buonanno, riaccende i riflettori sulla chiara e netta posizione di Manoccio nei confronti dei <strong>\u201ccentri di detenzione<\/strong>\u201d costruiti dal Governo Meloni in Albania, diventati operativi nell&#8217;ottobre del 2024 e ancora vuoti.<\/p>\n<p>\u00abQuesto caso &#8211; afferma il presidente Manoccio-\u00a0 \u00e8 ormai diventato il paradosso europeo, tanto che le testate nazionali estere chiedono conto di quanto sta accadendo. Del resto -continua- sono diversi mesi che protestiamo contro questo modo scellerato di fare politica contro i migranti. Da noi ad Acquaformosa continuiamo ad accogliere la gente che chiede asilo e questo ci arricchisce. Un grazie speciale &#8211; conclude &#8211; va al prestigioso organo di informazione \u201cLe Monde\u201d per aver dedicato questo spazio al nostro piccolo grande mondo\u00bb.<\/p>\n<p>Nell&#8217;articolo Manoccio interviene sul controverso accordo tra la presidente del Consiglio, Giorgia Meloni, e il suo omologo albanese, e sui 3mila posti nei due centri di detenzione costruiti in Albania per migranti clandestini restano vuoti. I centri sono diventati operativi nell\u2019ottobre del 2024, ma i giudici italiani hanno respinto la detenzione dei primi due gruppi di uomini che vi furono trasferiti e che furono poi riportati nella Penisola. Ora la Corte di Giustizia dell\u2019Unione Europea dovr\u00e0 riesaminare la questione, ma nel frattempo i trasferimenti si sono fermati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACQUAFORMOSA (CS) &#8211; Sul sito del quotidiano francese \u201cLe Monde\u201d, sabato 11 gennaio, \u00e8 apparso un articolo dedicato all&#8217;azione svolta ormai da anni dall&#8217;Associazione \u201cDon Vincenzo Matrangolo\u201d in tema di migranti. \u201cIn Calabria, la migrazione nelle vene di Giovanni Manoccio\u201d \u00e8 il titolo che il giornale ha voluto dare all&#8217;articolo proprio per enfatizzare l&#8217;impegno e [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":249050,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-249045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=249045"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/249050"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=249045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=249045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=249045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}