{"id":249268,"date":"2025-01-15T16:00:34","date_gmt":"2025-01-15T15:00:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=249268"},"modified":"2025-01-15T15:15:07","modified_gmt":"2025-01-15T14:15:07","slug":"diamante-installata-centralina-per-monitorare-lesposizione-ai-campi-elettromagnetici","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/diamante-installata-centralina-per-monitorare-lesposizione-ai-campi-elettromagnetici\/","title":{"rendered":"Diamante, installata centralina per monitorare l&#8217;esposizione ai campi elettromagnetici"},"content":{"rendered":"<p>DIAMANTE (CS) &#8211; <strong>Installata a Diamante la centralina per controllare l&#8217;esposizione ai campi elettromagnetici sul territorio comunale<\/strong>.<strong> L&#8217;ente locale di Diamante \u00e8 il primo in provincia di Cosenza ad aver sottoscritto un protocollo d&#8217;intesa con Arpacal per il monitoraggio in continuo dei cem<\/strong><\/p>\n<p>La sinergia tra il Comune di Diamante e l&#8217;Arpacal ha permesso, oggi 15 gennaio, l&#8217;installazione della <strong>centralina &#8220;Narda AMB-8059&#8221;<\/strong>. Dispositivo con il quale, rispetto al monitoraggio tradizionale dei campi elettromagnetici, si <strong>terranno sotto controllo le esposizioni della popolazione e saranno rilevati, in modo tempestivo, eventuali superamenti dei valori normativi.<\/strong> Nello specifico, i dati trasmessi dalla centralina in continuo e verificati da Arpacal \u2013 che si affiancano e integrano quelli delle attivit\u00e0 di monitoraggio e controllo che l&#8217;Agenzia svolge nel territorio \u2013 garantiscono il controllo costante di aree del territorio urbano, caratterizzato da molteplici fonti di pressione (stazioni radio base per la telefonia cellulare e impianti radiotelevisivi).<\/p>\n<h3><strong>Come funziona la centralina\u00a0&#8220;Narda AMB-8059&#8221;<\/strong><\/h3>\n<p>La centralina \u00e8 una &#8220;stazione di misura&#8221;. Pertanto, la sua collocazione rappresenta anche un sito di monitoraggio che avviene su indicazioni tecniche dell&#8217;Arpacal, <strong>dando priorit\u00e0 ai siti ritenuti pi\u00f9 critici (per numero e tipologia di impianti presenti) o pi\u00f9 delicati (asili, scuole eccetera) su segnalazioni del Comune<\/strong>. I dati acquisiti rilevano i livelli di campo elettrico presenti e le loro variazioni nel tempo. Quindi la centralina \u2013 che \u00e8 ricollocabile in altre postazioni \u2013 fornir\u00e0 un&#8217;analisi della variabilit\u00e0 temporale e di situazioni complesse, dovute alla presenza di molteplici sorgenti che variano nel tempo. Arpacal spiega che tali &#8220;campagne di monitoraggio hanno in genere una durata variabile da un minimo di qualche giorno ad un massimo di due o tre mesi, in base alla criticit\u00e0 dei valori rilevati, alla variabilit\u00e0 delle sorgenti ed alla disponibilit\u00e0 delle strutture ospitanti. Sono generalmente svolte in prossimit\u00e0 di impianti per telefonia mobile (SRB) a causa della maggior diffusione delle SRB nei centri abitati, a pi\u00f9 alta densit\u00e0 di popolazione potenzialmente esposta. In misura minore nei siti con impianti radiotelevisivi (RTV) o misti. Nel periodo di misura (e per tutta la durata della campagna) <strong>i dati rilevati vengono trasmessi automaticamente al centro di acquisizione, circa ogni 24 ore<\/strong>. Il personale Arpacal effettua quindi la validazione dei dati. I casi di superamento confermati sono segnalati alle autorit\u00e0 competenti e costantemente monitorati fino a risanamento concluso&#8221;.<\/p>\n<h3><strong>Bartalotta: &#8220;Soddisfatti, giorno importante per Diamante&#8221;<\/strong><\/h3>\n<p>Soddisfatto l&#8217;assessore alle Attivit\u00e0 Istituzionali del Comune di Diamante,<strong> Francesco Bartalotta<\/strong>: &#8220;\u00c8 un giorno importante per il territorio comunale di Diamante: entra nel vivo, infatti, il protocollo d&#8217;intesa che consente, con il supporto dell&#8217;Arpacal, di controllare, attraverso una centralina di nuova generazione, le esposizioni della popolazione ai campi elettromagnetici. L&#8217;iniziativa, voluta sin dall&#8217;insediamento dall&#8217;Amministrazione comunale guidata dal <strong>sindaco Achille Ordine<\/strong>, rappresenta un&#8217;importante sinergia tra Comune e Arpacal, per assicurare un monitoraggio costante dei siti che presentano maggiore esposizione ai cem. Il nostro Comune \u2013 precisa l&#8217;assessore \u2013 \u00e8 il primo in provincia di Cosenza ad aver sottoscritto questo accordo con Arpacal per il monitoraggio in continuo dei campi elettromagnetici. La misurazione sar\u00e0 effettuata con la centralina di modello analogo a quelle in uso all&#8217;Arpacal. L&#8217;attivazione di questa centralina nella nostra Citt\u00e0 \u2013 conclude l&#8217;assessore Bartalotta \u2013 \u00e8 un importante punto di partenza per la tutela della popolazione e la salvaguardia dell&#8217;ambiente dall&#8217;esposizione a campi elettrici, magnetici ed elettromagnetici non ionizzanti. Ringrazio il Commissario straordinario Arpacal Michelangelo Iannone, gli ingegneri Francesca Tarsia e Giuseppe Garofalo del Dipartimento Arpacal di Cosenza, e tutti i tecnici dell&#8217;Agenzia regionale&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DIAMANTE (CS) &#8211; Installata a Diamante la centralina per controllare l&#8217;esposizione ai campi elettromagnetici sul territorio comunale. L&#8217;ente locale di Diamante \u00e8 il primo in provincia di Cosenza ad aver sottoscritto un protocollo d&#8217;intesa con Arpacal per il monitoraggio in continuo dei cem La sinergia tra il Comune di Diamante e l&#8217;Arpacal ha permesso, oggi [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":249273,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-249268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=249268"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249268\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/249273"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=249268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=249268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=249268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}