{"id":249381,"date":"2025-01-17T08:40:55","date_gmt":"2025-01-17T07:40:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=249381"},"modified":"2025-01-17T11:38:53","modified_gmt":"2025-01-17T10:38:53","slug":"terzo-megalotto-della-statale-106-le-estorsioni-con-iva-della-cosca-abbruzzese-forastefano-sei-arresti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/terzo-megalotto-della-statale-106-le-estorsioni-con-iva-della-cosca-abbruzzese-forastefano-sei-arresti\/","title":{"rendered":"Terzo Megalotto della Statale 106: le estorsioni con Iva della cosca Abbruzzese Forastefano, sei arresti"},"content":{"rendered":"<p>CATANZARO &#8211; Operazione alle prime ore di oggi dagli agenti del Centro Operativo della Direzione Investigativa Antimafia (DIA) di Catanzaro, che hanno eseguito sei misure cautelari. Le accuse sono, a vario titolo, di estorsione aggravata dal metodo mafioso e istigazione alla corruzione e scaturiscono da un&#8217;indagine partita dalla denuncia di un imprenditore edile, vittima di una <strong>richiesta estorsiva di 150mila euro,<\/strong> equivalente al <strong>3% di un appalto da 5 milioni di euro relativo alla costruzione del \u201cTerzo Megalotto<\/strong>\u201d della Statale <strong>106<\/strong>. L\u2019opera, di rilevanza strategica, si trova in un territorio storicamente influenzato dalla criminalit\u00e0 organizzata, e per questo soggetta a un attento monitoraggio delle dinamiche criminali.<\/p>\n<p>Grazie ad intercettazioni telefoniche, ambientali e telematiche, e dall\u2019analisi di documentazione fiscale, bancaria e amministrativa, gli investigatori della Dia hanno delineato il <strong>sistema di pagamento estorsivo<\/strong>. A livello indiziario, \u00e8 emerso che le somme richieste venivano ricavate tramite sovrafatturazioni messe in atto da ditte colluse, utilizzando documenti falsi per simulare consegne di materiali e prestazioni sovradimensionate. Queste somme sarebbero confluite nelle casse della cosca di \u2018ndrangheta <strong>Abbruzzese di Cassano all\u2019Ionio<\/strong>.<\/p>\n<p>Tra le accuse figura anche il reato di <strong>istigazione alla corruzione<\/strong>: uno degli indagati infatti, avrebbe offerto 20.000 euro al <strong>capocantiere di una societ\u00e0<\/strong> a partecipazione statale per falsificare i certificati di stato avanzamento lavori (SAL) relativi allo smaltimento dell\u2019acqua. Disposto anche il <strong>sequestro preventivo di tre societ\u00e0 e dei relativi complessi aziendali<\/strong>, ritenuti strumenti funzionali alla realizzazione delle attivit\u00e0 illecite.<\/p>\n<h4><strong>Estorsioni con Iva<\/strong><\/h4>\n<p>Il sistema adottato era quello delle sovrafatturazioni a ditte compiacenti con la cosca, per pagare le estorsioni del 3% sul valore dell&#8217;appalto. Cos\u00ec la <strong>cosca Abbruzzese Forastefano<\/strong> tentava di eludere i controlli delle forze dell&#8217;ordine sui lavori del &#8220;Terzo Megalotto&#8221; della statale 106, il pi\u00f9 grande appalto in Calabria con un valore totale di 1,3 miliardi.<\/p>\n<p>Tra gli arrestati figura il reggente della cosca Abbruzzese Forastefano all&#8217;epoca dei fatti, ovvero, il 2022, Leonardo Abbruzzese detto &#8220;Nino&#8221;, attualmente detenuto al 41 bis dopo essere stato arrestato il 6 novembre 2023 in Puglia dopo un periodo di latitanza perch\u00e9 coinvolto <strong>nell&#8217;operazione Athena<\/strong>, un capocantiere, il suo autista e tre imprenditori titolari di aziende ritenute compiacenti con la &#8216;ndrangheta.<\/p>\n<h4><strong> L&#8217;inchiesta non riguarda il contraente dell&#8217;opera Webuild<\/strong><\/h4>\n<p>La societ\u00e0, hanno sottolineato fonti investigative, sempre collaborativa con le forze dell&#8217;ordine nel fronteggiare i tentativi di infiltrazione delle cosche nei lavori dell&#8217;opera. Da quanto emerso, le somme richieste venivano <strong>ricavate tramite sovrafatturazioni messe in atto da ditte &#8220;colluse&#8221;, con l&#8217;utilizzo di documentazione falsa<\/strong> che simulava consegne di materiali e prestazioni di servizi sovradimensionate, cos\u00ec da contenere, ab origine, la quota parte destinata al pagamento dell&#8217;estorsione, che sarebbe confluita nelle casse della cosca Abbruzzese di Cassano all&#8217;Ionio.<\/p>\n<p>A fare da intermediario tra le imprese vittime e la cosca sarebbe stato un<strong> capocantiere di un&#8217;azienda<\/strong> <strong>non coinvolta nell&#8217;inchiesta<\/strong> che indicava agli imprenditori estorti a quali ditte sovrafatturare per pagare la tangente. Uno degli arrestati \u00e8 indagato anche per istigazione alla corruzione. Secondo l&#8217;accusa avrebbe promesso al capocantiere di una societ\u00e0 a partecipazione statale appaltante dei lavori, incaricato di pubblico servizio, circa 20.000 per indurlo a falsificare i certificati di stato avanzamento lavori relativi allo smaltimento dell&#8217;acqua da parte dell&#8217;azienda incaricata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Operazione alle prime ore di oggi dagli agenti del Centro Operativo della Direzione Investigativa Antimafia (DIA) di Catanzaro, che hanno eseguito sei misure cautelari. Le accuse sono, a vario titolo, di estorsione aggravata dal metodo mafioso e istigazione alla corruzione e scaturiscono da un&#8217;indagine partita dalla denuncia di un imprenditore edile, vittima di [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":240487,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19,135],"class_list":["post-249381","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-calabria","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=249381"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/240487"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=249381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=249381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=249381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}