{"id":249438,"date":"2025-01-17T19:57:30","date_gmt":"2025-01-17T18:57:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=249438"},"modified":"2025-01-17T19:57:30","modified_gmt":"2025-01-17T18:57:30","slug":"planetario-nel-degrado-scoppia-la-querelle-botta-e-risposta-tra-maggioranza-e-minoranza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/planetario-nel-degrado-scoppia-la-querelle-botta-e-risposta-tra-maggioranza-e-minoranza\/","title":{"rendered":"Planetario nel degrado, scoppia la querelle: botta e risposta tra maggioranza e minoranza"},"content":{"rendered":"<p>COSENZA &#8211; Prosegue la <strong><a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/planetario-di-cosenza-tra-degrado-e-vandalismo-occhiuto-proteggere-e-valorizzare-un-patrimonio-della-citta\" target=\"_blank\" rel=\"noopener\">polemica sul Planetario<\/a><\/strong> di Cosenza: la struttura versa ormai in uno stato di abbandono da anni. Alle dichiarazioni delegato al patrimonio del sindaco, <strong>Antonello Costanzo<\/strong> &#8211; che si scaglia contro l&#8217;ex sindaco di Cosenza dopo quanto dichiarato sulla struttura &#8211; segue la replica dei<strong> consiglieri comunali di opposizione<\/strong>: <strong>Caruso, Cito, D\u2019Ippolito, Dodaro, Luberto, Lucanto, Ruffolo, Spadafora, Spataro.<\/strong><\/p>\n<h3><strong>Costanzo: &#8220;Duro colpo di Occhiuto alla memoria di Piperno&#8221;<\/strong><\/h3>\n<p>&#8220;Duro colpo certamente alla memoria di Franco Piperno, ma duro colpo, soprattutto, alla citt\u00e0 ed ai cosentini che ha inferto proprio Mario Occhiuto, che oggi tenta di fare un indecente scarica barile. Ed, infatti, se la sua amministrazione avesse pagato lo Starmaster ZMP della Zeiss, che dovremo pagare noi per 450 mila euro, ed avesse progettato e realizzato per il funzionamento del Planetario un piano di efficientamento energetico, anzich\u00e9 fare inaugurazioni faraoniche e costosissime, le cose oggi andrebbero diversamente&#8221;. Lo afferma <strong>Antonello Costanzo, delegato al patrimonio del sindaco Franz Caruso.<\/strong><\/p>\n<p>&#8220;Il sindaco Franz Caruso, purtroppo, h<strong>a ereditato dalla passata amministrazione comunale di centrodestra solo disastri<\/strong>, che sta risolvendo e gestendo nel migliore dei modi, e tra questi c&#8217;\u00e8 proprio il Planetario che era gi\u00e0 chiuso da tempo al nostro insediamento e che aveva avuto solo 5 mesi di attivit\u00e0, certamente a causa della pandemia, ma che successivamente non \u00e8 stato pi\u00f9 possibile riaprire perch\u00e9 lasciato nell&#8217;incuria e nell&#8217;abbandono. Innanzitutto, la struttura non \u00e8 stata mai affidata all&#8217;azienda che nel giugno 2020 ha partecipato all&#8217;apposito avviso risultando con la migliore valutazione, per gli alti costi di energia elettrica, lasciandolo per come detto chiuso ed anche privo di manutenzione e controllo. L&#8217;opera, inoltre, su cui \u00e8 necessario intervenire perch\u00e9 risulta gi\u00e0 ammalorata in molte parti, con evidente scrostatura di vernice, \u00e8 incompleta perch\u00e9 non \u00e8 stato realizzato neanche il muro di recinzione intorno.<\/p>\n<p>Per queste ragioni ritengo veramente <strong>vergognose le dichiarazioni rilasciate oggi dal senatore<a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/planetario-di-cosenza-tra-degrado-e-vandalismo-occhiuto-proteggere-e-valorizzare-un-patrimonio-della-citta\" target=\"_blank\" rel=\"noopener\"> Mario Occhiuto<\/a><\/strong> che non meriterebbero neanche una risposta, che, invece, si d\u00e0 solo per amore della verit\u00e0 ed a beneficio dell&#8217;opinione pubblica. Non possiamo permettere, infatti, che i cosentini vengano ancora turlupinati e presi in giro da chi come l&#8217;attuale senatore ai fatti ha preferito sempre e solo annunci ed operazioni di facciata che hanno lasciato Cosenza nella melma da cui Franz Caruso e tutti noi la stiamo rimuovendo, ridandole dignit\u00e0 e facendole riconquistare il prestigio che merita&#8221;.<\/p>\n<h3><strong>&#8220;Indecenti le affermazioni del consigliere Costanzo&#8221;<\/strong><\/h3>\n<p>&#8220;Ci lasciano allibiti le indecenti affermazioni del consigliere Costanzo, delegato al patrimonio, riguardo ai contenuti del post con cui il Senatore Occhiuto ha inteso sensibilizzare, con spirito costruttivo, l\u2019attuale Amministrazione ad un\u2019azione di salvaguardia e valorizzazione di una risorsa importante come il Planetario di Cosenza&#8221;. Cos\u00ec dichiarano i consiglieri comunali <strong>Caruso, Cito, D\u2019Ippolito, Dodaro, Luberto, Lucanto, Ruffolo, Spadafora, Spataro.<\/strong><\/p>\n<p>In qualit\u00e0 di consiglieri di opposizione, attendiamo da diversi mesi che lo stesso Costanzo venga a riferire della propria attivit\u00e0 nella Commissione competente, avendo in passato egli stesso affermato pubblicamente e perentoriamente che entro la scorsa estate ci sarebbero stati sviluppi nel recupero e rifunzionalizzazione della struttura ormai abbandonata dall\u2019attuale Amministrazione nel degrado pi\u00f9 totale. Evidentemente, il Consigliere Costanzo, che nulla ha prodotto fino ad oggi di buono nell\u2019esercizio della propria delega, piuttosto che riferire nelle sedi istituzionali, dove potrebbe solo dare evidenza del proprio immobilismo, della propria inerzia e della propria incapacit\u00e0 amministrativa, preferisce agire con delle sortite irriguardose, limitando i propri sforzi a vergare ignobili comunicati concepiti nelle chiuse stanze di palazzo dei Bruzi.<\/p>\n<p>Conoscendo la storia del Planetario, per aver concretamente contribuito alla sua realizzazione, ricordiamo al consigliere Costanzo che la lente della Zeiss, al momento del primo insediamento dell\u2019allora Sindaco Occhiuto, risultava gi\u00e0 pagata da chi lo aveva preceduto, pur non essendo stata ancora realizzata la struttura: circostanza che indusse lo stesso Occhiuto a diffidare la Zeiss minacciando una denuncia. <strong>La risorsa del Planetario, ereditata dall\u2019attuale Amministrazione perfettamente funzionante, \u00e8 stata trascurata anche nella vigilanza<\/strong>, posto che sono stati perpetrati ben due atti vandalici, con notevoli danni, a causa dell\u2019inefficienza del sistema di allarme e anti-intrusione, del quale si \u00e8 trascurato finanche di caricare le batterie.<\/p>\n<p>Inoltre, le potenzialit\u00e0 di reddito della struttura stessa, la rendono appetibile per molti privati, consapevoli che potrebbero ammortizzare nel breve periodo anche i costi del riefficientamento energetico, resosi necessario per l\u2019incremento dei costi dell\u2019energia (costi imprevisti e imprevedibili all\u2019epoca di realizzazione dell\u2019opera). <strong>Le soluzioni per il recupero e la valorizzazione di questa evolutiva, lungimirante risorsa culturale ci sono, eccome.<\/strong> Mancano, evidentemente, capacit\u00e0 e volont\u00e0 di perseguire strade virtuose, atteso che, a pi\u00f9 di tre anni dall\u2019insediamento, il Sindaco e Giunta comunale, nonostante i proclami e le dichiarazioni d\u2019intenti, nulla hanno prodotto in tale direzione&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Prosegue la polemica sul Planetario di Cosenza: la struttura versa ormai in uno stato di abbandono da anni. Alle dichiarazioni delegato al patrimonio del sindaco, Antonello Costanzo &#8211; che si scaglia contro l&#8217;ex sindaco di Cosenza dopo quanto dichiarato sulla struttura &#8211; segue la replica dei consiglieri comunali di opposizione: Caruso, Cito, D\u2019Ippolito, [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":121742,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-249438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=249438"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/121742"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=249438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=249438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=249438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}