{"id":249562,"date":"2025-01-26T21:00:47","date_gmt":"2025-01-26T20:00:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=249562"},"modified":"2025-01-25T12:49:30","modified_gmt":"2025-01-25T11:49:30","slug":"litalia-e-il-terzo-paese-piu-colpito-da-campagna-virus-che-usa-lintelligenza-artificiale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/litalia-e-il-terzo-paese-piu-colpito-da-campagna-virus-che-usa-lintelligenza-artificiale\/","title":{"rendered":"L&#8217;Italia \u00e8 il terzo paese pi\u00f9 colpito da campagna virus che usa l&#8217;Intelligenza Artificiale"},"content":{"rendered":"<p>COSENZA &#8211; Come indicato da esperti del settore nei mesi scorsi, crescono le <strong>minacce informatiche che sfruttano<a href=\"https:\/\/quicosenza.it\/news\/calabria\/una-legge-regionale-sullintelligenza-artificiale-con-registro-regionale-e-apposito-ufficio\" target=\"_blank\" rel=\"noopener\"> l&#8217;intelligenza artificiale<\/a>.<\/strong><\/p>\n<p>Gli analisti dell&#8217;agenzia di sicurezza Check Point Research hanno scoperto <strong>FunkSec, un nuovo gruppo che usa l&#8217;<a href=\"https:\/\/it.wikipedia.org\/wiki\/Intelligenza_artificiale\" target=\"_blank\" rel=\"noopener\">IA<\/a> per creare virus e lanciarli in rete<\/strong>. <strong>L&#8217;Italia \u00e8 il terzo paese al mondo<\/strong> pi\u00f9 colpito con il 5% degli attacchi globali. Al primo posto ci sono gli Stati Uniti, con il 21%, seguiti dall&#8217;India, al 16%. L&#8217;Italia condivide la terza piazza con il Brasile.<\/p>\n<p>l gruppo, emerso alla fine del 2024, secondo gli esperti, avrebbe legami con membri che operano in Algeria, precedentemente impegnati in attivit\u00e0 di cosiddetto &#8220;hacktivismo&#8221;, ossia attivismo legato a violazioni informatiche, a scopo politico o sociale. Per Check Point Research, l&#8217;ascesa nell&#8217;uso dell&#8217;IA da parte dei criminali sta portando ad un aumento non solo del raggio d&#8217;azione degli hacker, con l&#8217;opportunit\u00e0 di affidarsi a software automatizzati per inviare virus via email o messaggi di testo e chat, ma anche del numero stesso degli attori che creano le campagne, con un ingresso pi\u00f9 basso nel panorama dell&#8217;hacking, con minori competenze necessarie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Come indicato da esperti del settore nei mesi scorsi, crescono le minacce informatiche che sfruttano l&#8217;intelligenza artificiale. Gli analisti dell&#8217;agenzia di sicurezza Check Point Research hanno scoperto FunkSec, un nuovo gruppo che usa l&#8217;IA per creare virus e lanciarli in rete. L&#8217;Italia \u00e8 il terzo paese al mondo pi\u00f9 colpito con il 5% [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":249563,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-249562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=249562"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/249563"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=249562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=249562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=249562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}