{"id":249705,"date":"2025-01-21T23:02:37","date_gmt":"2025-01-21T22:02:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=249705"},"modified":"2025-01-23T07:08:39","modified_gmt":"2025-01-23T06:08:39","slug":"sofia-e-stata-ritrovata-il-nonno-ringrazio-tutti-si-e-mobilitata-la-citta-e-la-notizia-piu-bella-del-mondo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sofia-e-stata-ritrovata-il-nonno-ringrazio-tutti-si-e-mobilitata-la-citta-e-la-notizia-piu-bella-del-mondo\/","title":{"rendered":"Sofia \u00e8 stata ritrovata, il nonno \u00abringrazio tutti, si \u00e8 mobilitata la citt\u00e0, \u00e8 la notizia pi\u00f9 bella del mondo\u00bb &#8211; VIDEO"},"content":{"rendered":"<p>COSENZA &#8211; Parla tra le lacrime, <strong>Mario Cavoto<\/strong>, il <strong>nonno paterno della piccola Sofia<\/strong>, la bimba di appena un giorno di vita che nel pomeriggio di oggi, era stata <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/shockcs-a-cosenza-neonata-rapita-al-sacro-cuore-si-indaga-sulle-telecamere-di-videosorveglianza\">rapita nella clinica<\/a> in cui \u00e8 venuta alla luce, la casa di cura Sacro Cuore. La piccola \u00e8 stata riportata in ambulanza alla clinica, in una culletta termica, e sta bene. Secondo quanto emerso, i due rapitori sarebbero stati fermati in contrada Rocchi a Rende dalla Polizia di Stato e, messi alle strette avrebbero indicato <strong>un appartamento di Castrolibero.\u00a0<\/strong><\/p>\n<p>L&#8217;operazione della polizia, coordinata dai dirigenti Gabriele Presti e Claudio Sole, \u00e8 scattata immediatamente e gli agenti si sono precipitati nella zona indicata dove per fortuna la piccola \u00e8 stata <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/ritrovatacs-la-piccolacs-sofia-la-neonata-rapita-al-sacro-cuore-di-cosenza\">ritrovata<\/a>, in un appartamento in via Almirante. Sul posto \u00e8 stata fatta arrivare un&#8217;ambulanza che ha poi prelevato la <strong>bambina e dopo averla riposta in una culletta termica l&#8217;ha riportata alla Clinica<\/strong>.<\/p>\n<p>La piccola, che sta bene, \u00e8 stata accolta tra gli applausi di un&#8217;intera citt\u00e0 che per ore \u00e8 stata in apprensione per le sue sorti. Il nonno in lacrime, attende davanti al Sacro Cuore: <strong>&#8220;\u00e8 la notizia pi\u00f9 bella del mondo&#8221;.\u00a0<\/strong>Intanto i due autori del rapimento, sono stati tratti in arresto e si trovano in Questura. Si tratta di <strong>Rosa Vespa, 51 anni di Cosenza e del marito Acqua Moses, di 43 anni, nigeriano<\/strong>.\u00a0Le indagini proseguono per accertare la dinamica e soprattutto il movente del rapimento della neonata.<\/p>\n<p>Secondo quanto emerso infatti, la <strong>donna sui social<\/strong> avrebbe nei giorni precedenti annunciato la nascita di un figlio. In pratica, secondo quanto emerso, avrebbe <strong>simulato per nove mesi la gravidanza<\/strong> e l&#8217;8 gennaio scorso aveva annunciato la nascita di un maschietto, Ansel, con un post su Facebook. Quando gli agenti sono entrati nella casa di Castrolibero, hanno trovato una <strong>sorta di festa in corso<\/strong>, insieme ad alcuni parenti e <strong>la piccola era stata vestita d&#8217;azzurro, come un maschietto.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Parla tra le lacrime, Mario Cavoto, il nonno paterno della piccola Sofia, la bimba di appena un giorno di vita che nel pomeriggio di oggi, era stata rapita nella clinica in cui \u00e8 venuta alla luce, la casa di cura Sacro Cuore. La piccola \u00e8 stata riportata in ambulanza alla clinica, in una [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":249707,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19,135],"class_list":["post-249705","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=249705"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/249707"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=249705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=249705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=249705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}