{"id":249803,"date":"2025-01-23T07:04:47","date_gmt":"2025-01-23T06:04:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=249803"},"modified":"2025-01-23T07:07:23","modified_gmt":"2025-01-23T06:07:23","slug":"traffico-di-droga-dal-sudamerica-con-voli-aerei-e-ovulatori-10-arresti-tra-italiani-e-colombiani","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/traffico-di-droga-dal-sudamerica-con-voli-aerei-e-ovulatori-10-arresti-tra-italiani-e-colombiani\/","title":{"rendered":"Traffico di droga dal Sudamerica con voli aerei e ovulatori, 10 arresti tra italiani e colombiani"},"content":{"rendered":"<p>CATANZARO &#8211; La guardia di finanza di Catanzaro, in collaborazione con il Servizio Centrale Investigazione Criminalit\u00e0 Organizzata e del Comando Provinciale Roma, stanno eseguendo dalle prime ore di oggi <strong>10 misure cautelari in carcere<\/strong> nei confronti di altrettanti soggetti, italiani e colombiani. Gli indagati sono accusati a vario titolo di aver promosso, organizzato e realizzato un <strong>intenso traffico di sostanze stupefacenti dal Sudamerica<\/strong>.<\/p>\n<p>Le indagini hanno permesso di accertare <strong>l\u2019operativit\u00e0 di alcuni trafficanti colombiani<\/strong> che rifornivano di cocaina organizzazioni criminali operanti in <strong>Calabria, Lazio e Veneto<\/strong>. Particolarmente attivo risultava un <strong>gruppo criminale operativo nella Capitale<\/strong>, il quale attraverso contatti diretti con i fornitori colombiani ha realizzato diverse importazioni di stupefacente, utilizzando i pi\u00f9 disparati metodi di spedizione e occultamento.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-249804 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/finanza-aeroporto-lamezia.jpg\" alt=\"\" width=\"413\" height=\"256\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/finanza-aeroporto-lamezia.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/finanza-aeroporto-lamezia-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/finanza-aeroporto-lamezia-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/finanza-aeroporto-lamezia-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/finanza-aeroporto-lamezia-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/finanza-aeroporto-lamezia-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/finanza-aeroporto-lamezia-356x220.jpg 356w\" sizes=\"auto, (max-width: 413px) 100vw, 413px\" \/><\/p>\n<p>Le Fiamme Gialle hanno accertato, in particolare, l\u2019impiego da parte dell\u2019organizzazione sia del<strong> mezzo aereo<\/strong>, con <strong>l\u2019ausilio di corrieri<\/strong> (anche <strong>ovulatori<\/strong>) <strong>nonch\u00e9 l\u2019utilizzo di voli charter e del vettore navale<\/strong>, pianificando di nascondere lo <strong>stupefacente nei motori dei container frigo.<\/strong><\/p>\n<h4>L&#8217;arresto di un ovulatore<\/h4>\n<p>L\u2019attivit\u00e0 ha consentito in occasione <strong>dell\u2019arresto di un ovulatore<\/strong> presso lo scalo aeroportuale di <strong>Fiumicino<\/strong>, di accertare come gli indagati avessero allestito un <strong>laboratorio per la trasformazione della cocaina<\/strong> (da liquida a solida), facendo appositamente trasferire in Italia un \u201cchimico\u201d colombiano che avrebbe curato tale attivit\u00e0, avendo l\u2019organizzazione pianificato successive e ingenti importazioni di stupefacente.<\/p>\n<p>Nell\u2019ambito dell\u2019operazione di oggi sono state impiegate unit\u00e0 cinofile antidroga del predetto Reparto e un cash dog del Gruppo Fiumicino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; La guardia di finanza di Catanzaro, in collaborazione con il Servizio Centrale Investigazione Criminalit\u00e0 Organizzata e del Comando Provinciale Roma, stanno eseguendo dalle prime ore di oggi 10 misure cautelari in carcere nei confronti di altrettanti soggetti, italiani e colombiani. Gli indagati sono accusati a vario titolo di aver promosso, organizzato e realizzato [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":249805,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19,135],"class_list":["post-249803","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-calabria","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=249803"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249803\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/249805"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=249803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=249803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=249803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}