{"id":249839,"date":"2025-01-23T13:38:07","date_gmt":"2025-01-23T12:38:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=249839"},"modified":"2025-01-23T13:38:07","modified_gmt":"2025-01-23T12:38:07","slug":"rende-m5s-aumenti-insostenibili-per-il-servizio-mensa-scolastico","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/rende-m5s-aumenti-insostenibili-per-il-servizio-mensa-scolastico\/","title":{"rendered":"Rende, M5S \u00abaumenti insostenibili per il servizio mensa scolastico\u00bb"},"content":{"rendered":"<p>RENDE &#8211; &#8220;Tantissimi utenti rendesi, tra scuole primarie e dell&#8217;infanzia, si trovano a dover fare i conti con un aumento <strong>indiscriminato delle tariffe del servizio mensa, che supera il 15%.<\/strong> Un incremento che penalizza economicamente le famiglie ed \u00e8 stato attuato in modo del tutto <strong>inaccettabile<\/strong>. Non solo: l&#8217;<strong>agevolazione per il secondo figlio \u00e8 stata eliminata<\/strong>, una decisione che pesa ancora di pi\u00f9 sui bilanci familiari gi\u00e0 messi a dura prova&#8221;. A renderlo noto \u00e8 il Gruppo Territoriale M5S di Rende che spiega come le famiglie si siano &#8220;trovate davanti a una vera e propria sorpresa: un aumento gi\u00e0 previsto ma non comunicato in tempo. Le condizioni di adesione al servizio, sottoscritte all&#8217;inizio dell&#8217;anno scolastico, sono state variate e molti genitori hanno scoperto solo a dicembre che le regole erano cambiate, un fatto che mina la fiducia nelle istituzioni locali&#8221;.<\/p>\n<p>&#8220;Come se non bastasse, il <strong>Comune ha introdotto modifiche anche ai criteri delle fasce ISEE<\/strong>, <strong>rendendo ancora pi\u00f9 difficile per numerose famiglie accedere alle agevolazioni<\/strong>. Questo ulteriore ostacolo contribuisce a creare un clima di incertezza e frustrazione.\u00a0Come Gruppo Territoriale M5S di Rende riteniamo inaccettabile che decisioni cos\u00ec importanti vengano prese senza la minima trasparenza e senza coinvolgere le famiglie, che ogni giorno si impegnano per garantire un&#8217;educazione dignitosa ai propri figli. Questo non \u00e8 solo un problema economico, ma una questione di giustizia sociale e rispetto dei diritti. Le <strong>famiglie di Rende meritano risposte e soluzioni<\/strong>, non sorprese amare e condizioni sempre pi\u00f9 gravose. Siamo al fianco di chi si oppone a queste decisioni e continueremo a lavorare per tutelare i diritti della comunit\u00e0&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; &#8220;Tantissimi utenti rendesi, tra scuole primarie e dell&#8217;infanzia, si trovano a dover fare i conti con un aumento indiscriminato delle tariffe del servizio mensa, che supera il 15%. Un incremento che penalizza economicamente le famiglie ed \u00e8 stato attuato in modo del tutto inaccettabile. Non solo: l&#8217;agevolazione per il secondo figlio \u00e8 stata [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":217937,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-249839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=249839"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/217937"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=249839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=249839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=249839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}