{"id":249840,"date":"2025-01-26T18:00:51","date_gmt":"2025-01-26T17:00:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=249840"},"modified":"2025-01-26T18:01:43","modified_gmt":"2025-01-26T17:01:43","slug":"san-giovanni-in-fiore-incontro-per-potenziare-i-servizi-sanitari-ulteriori-e-piu-complete-risposte","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/san-giovanni-in-fiore-incontro-per-potenziare-i-servizi-sanitari-ulteriori-e-piu-complete-risposte\/","title":{"rendered":"San Giovanni in Fiore, incontro per potenziare i servizi sanitari \u00abulteriori e pi\u00f9 complete risposte\u00bb"},"content":{"rendered":"<p>SAN GIOVANNI IN FIORE (CS) &#8211; Il prossimo <strong>30 gennaio<\/strong> il Direttore Generale dell&#8217;Azienda Sanitaria Provinciale di Cosenza, <strong>Antonio Graziano<\/strong>, ricever\u00e0 i capigruppo del Consiglio comunale la sindaca di San Giovanni in Fiore, Rosaria Succurro, per discutere del potenziamento dei servizi sanitari in un&#8217;ottica di collaborazione e miglioramento dei servizi sanitari sul territorio.<\/p>\n<p>Durante l&#8217;incontro si discuter\u00e0 delle strategie per il potenziamento dei servizi sanitari, con particolare attenzione alle esigenze della comunit\u00e0 locale. Sar\u00e0 un&#8217;occasione per affrontare tematiche cruciali come l&#8217;accesso alle cure, il potenziamento delle strutture sanitarie e la promozione della salute pubblica.<\/p>\n<p>Succurro, ha dato atto che \u00ab<strong>l\u2019attuale direzione dell&#8217;Asp ha finora fatto del suo meglio<\/strong> per migliorare la sanit\u00e0 a San Giovanni in Fiore, ascoltando le nostre richieste, ma \u00e8 arrivato il momento di avere ulteriori e pi\u00f9 complete risposte\u00bb, aggiungendo che \u00absi ottengono risultati quando si evitano strumentalizzazioni e divisioni. Senza distinzioni politiche, il consiglio comunale aveva gi\u00e0 votato alcune proposte sulla nostra sanit\u00e0, confermando che sul diritto alla salute non \u00e8 giusto aprire scontri e soprattutto non serve. Vogliamo tutti il bene dei sangiovannesi e sono convinta che anche stavolta sapremo andare nella stessa direzione\u00bb.<\/p>\n<p>La sindaca ha anche sottolineato l&#8217;importanza della sinergia tra istituzioni locali e sanitarie per garantire un servizio sempre pi\u00f9 efficiente e rispondente ai bisogni dei cittadini: \u00abIl confronto con i <strong>rappresentanti del Consiglio Comunale<\/strong> \u00e8 fondamentale per comprendere al meglio le necessit\u00e0 del nostro territorio e per lavorare insieme a soluzioni concrete\u00bb. L&#8217;impegno sar\u00e0 poi aggiornare la cittadinanza dopo l\u2019incontro, e presto si terr\u00e0 anche un consiglio comunale aperto alle associazioni e alle forze sindacali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN GIOVANNI IN FIORE (CS) &#8211; Il prossimo 30 gennaio il Direttore Generale dell&#8217;Azienda Sanitaria Provinciale di Cosenza, Antonio Graziano, ricever\u00e0 i capigruppo del Consiglio comunale la sindaca di San Giovanni in Fiore, Rosaria Succurro, per discutere del potenziamento dei servizi sanitari in un&#8217;ottica di collaborazione e miglioramento dei servizi sanitari sul territorio. Durante l&#8217;incontro [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":248819,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-249840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=249840"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/249840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/248819"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=249840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=249840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=249840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}